{"id":181687,"date":"2025-01-14T20:18:00","date_gmt":"2025-01-15T04:18:00","guid":{"rendered":"https:\/\/robotics.omron.com\/case-studies\/como-etiquetar-werfen-1000-viales-por-hora-con-automatizacion\/"},"modified":"2026-07-23T15:59:51","modified_gmt":"2026-07-23T22:59:51","slug":"automated-vial-labelling-omron-werfen","status":"publish","type":"case-study","link":"https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/","title":{"rendered":"\u00bfC\u00f3mo etiquetar werfen 1000 viales por hora con automatizaci\u00f3n?"},"content":{"rendered":"<section class=\"post-head overflow-y-visible overflow-x-clip\">\n\t\n\t<div class=\"container\">\n\t\t<div class=\"~pt-[4.5rem]\/[5.625rem] relative\">\n\t\t\t<div class=\"flex flex-col ~gap-[3rem]\/[4rem]\">\n\t\t\t\t<div class=\"flex flex-col ~gap-[4rem]\/[6rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<a class=\"post-back\" href=\"https:\/\/robotics.omron.com\/case-studies\/\" target=\"_self\">\n\t\t\t\t\t\t\t<svg width=\"13\" height=\"13\" viewbox=\"0 0 13 13\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t\t\t<path d=\"M4.44255 10.375L1.15088 6.94618L4.44254 3.51736\" stroke=\"#262626\" stroke-opacity=\"0.6\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t\t\t\t\t<path d=\"M11.9859 0.500098L11.9859 5.84905C11.9859 6.45472 11.4943 6.94627 10.8887 6.94627L1.01367 6.94627\" stroke=\"#262626\" stroke-opacity=\"0.6\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t\t\t\t<\/svg>\n\n\t\t\t\t\t\t\t<p>Volver a casos de estudio<\/p>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\n\t        <h1 class=\"main-title h2 flex flex-wrap\"><span class=\"outer-word\"><span class=\"inner-word\">\u00bfC\u00f3mo&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">etiquetar&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">werfen&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">1000&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">viales&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">por&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">hora&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">con&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">automatizaci\u00f3n?&nbsp;<\/span><\/span><\/h1>\n    \t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"flex flex-col ~gap-[1.25rem]\/[1.5rem]\">\n\t\t\t\t\t<div class=\"flex justify-between items-center\">\n\t\t\t\t\t\t\t<div class=\"flex gap-[0.5rem] items-center \">\n\t\t<div class=\"w-[0.5rem] h-[0.5rem] shrink-0 bg-green\"><\/div>\n\t\t<small class=\"text-black-60\">Caso pr\u00e1ctico<\/small>\n\t<\/div>\n                        \n                        \t\t\t\t\t\t                            \t\t\t\t\t<\/div>\n\n                    \t\t\t\t\t<div class=\"~h-[16.25rem]\/[42.875rem] w-[104vw] relative center-x\">\n\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"main-image rounded-[0.5rem] overflow-hidden absolute center-xy w-full h-full object-cover\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Operators-Cell.jpg\"  loading=\"eager\" alt=\"C\u00e9lula-de-operadores-Macco-Werfen\">\n\t\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"content-rich-text-rc-start  is-blog-post\">\n\t\n\t\t\n\t<div class=\"inner ~pt-[7.25rem]\/[10.25rem] sb-xxl\">\n\t\t<div class=\"container\">\n\t\t\t<div class=\"content-outer\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"social-share-container\">\n\t\t\t\t\t\t<div class=\"social-share-inner\">\n\t\t\t\t\t\t\t<small class=\"text-black-60\">Comparte<\/small>\n\n\t\t\t\t\t\t\t<div class=\"social-shares\">\n\t\t\t\t\t\t\t\t<a class=\"social-share\" href=\"https:\/\/twitter.com\/share?url=https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/\" target=\"_blank\" rel=\"nofollow noreferrer noopen\">\n\t\t\t\t\t\t\t\t\t<svg width=\"16\" height=\"16\" viewbox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t\t\t\t\t<path d=\"M11.9539 1.68994H14.0624L9.45607 6.95462L14.875 14.1187H10.632L7.30877 9.77372L3.50622 14.1187H1.39652L6.3234 8.4875L1.125 1.68994H5.47569L8.47962 5.6614L11.9539 1.68994ZM11.2139 12.8567H12.3822L4.84087 2.88565H3.58716L11.2139 12.8567Z\" fill=\"#262626\"\/>\n\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t<a class=\"social-share\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&amp;url=https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/\" target=\"_blank\" rel=\"nofollow noreferrer noopen\">\n\t\t\t\t\t\t\t\t\t<svg width=\"16\" height=\"16\" viewbox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t\t\t\t\t<path d=\"M3.99003 5.32556H0.978752C0.845107 5.32556 0.736816 5.4339 0.736816 5.5675V15.2414C0.736816 15.3751 0.845107 15.4834 0.978752 15.4834H3.99003C4.12367 15.4834 4.23196 15.3751 4.23196 15.2414V5.5675C4.23196 5.4339 4.12367 5.32556 3.99003 5.32556Z\" fill=\"#262626\"\/>\n\t\t\t\t\t\t\t\t\t\t<path d=\"M2.48658 0.516418C1.3909 0.516418 0.499512 1.40684 0.499512 2.50131C0.499512 3.59626 1.3909 4.48701 2.48658 4.48701C3.58138 4.48701 4.47204 3.59621 4.47204 2.50131C4.47209 1.40684 3.58138 0.516418 2.48658 0.516418Z\" fill=\"#262626\"\/>\n\t\t\t\t\t\t\t\t\t\t<path d=\"M11.6516 5.08533C10.4422 5.08533 9.54815 5.60525 9.00588 6.196V5.5677C9.00588 5.4341 8.89759 5.32576 8.76394 5.32576H5.88012C5.74647 5.32576 5.63818 5.4341 5.63818 5.5677V15.2416C5.63818 15.3753 5.74647 15.4836 5.88012 15.4836H8.88481C9.01846 15.4836 9.12675 15.3753 9.12675 15.2416V10.4553C9.12675 8.84239 9.56485 8.21404 10.6892 8.21404C11.9137 8.21404 12.011 9.22136 12.011 10.5383V15.2417C12.011 15.3753 12.1192 15.4836 12.2529 15.4836H15.2587C15.3923 15.4836 15.5006 15.3753 15.5006 15.2417V9.93536C15.5006 7.53705 15.0433 5.08533 11.6516 5.08533Z\" fill=\"#262626\"\/>\n\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t<a class=\"social-share\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/\" target=\"_blank\" rel=\"nofollow noreferrer noopen\">\n\t\t\t\t\t\t\t\t\t<svg width=\"8\" height=\"16\" viewbox=\"0 0 8 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t\t\t\t\t<path d=\"M0.453361 8.489H2.0976V15.2581C2.0976 15.3917 2.20589 15.5 2.33954 15.5H5.12741C5.26105 15.5 5.36935 15.3917 5.36935 15.2581V8.52089H7.25954C7.38244 8.52089 7.48584 8.42866 7.49988 8.30658L7.78696 5.81455C7.79485 5.74598 7.77312 5.67732 7.72725 5.62589C7.68133 5.5744 7.61562 5.54494 7.54667 5.54494H5.36944V3.98281C5.36944 3.5119 5.62299 3.27311 6.12312 3.27311C6.19439 3.27311 7.54667 3.27311 7.54667 3.27311C7.68031 3.27311 7.7886 3.16477 7.7886 3.03118V0.743726C7.7886 0.610081 7.68031 0.50179 7.54667 0.50179H5.58481C5.57097 0.501113 5.54025 0.5 5.49496 0.5C5.15455 0.5 3.97134 0.566823 3.0367 1.42666C2.00112 2.3795 2.14507 3.52037 2.17947 3.71818V5.54489H0.453361C0.319716 5.54489 0.211426 5.65318 0.211426 5.78682V8.24702C0.211426 8.38066 0.319716 8.489 0.453361 8.489Z\" fill=\"#262626\"\/>\n\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"absolute bottom-0 w-full center-x min-w-[90rem]\">\n\t\t\t<div class=\"lottie\" data-json=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/json\/lottie\/green-trail-on-light.json\"><\/div>\n\t\t<\/div>\n\t<\/section>\n\t<section class=\"post-three-column-icon-text\">\n\t\t\n\t\t<div class=\"icon-container grid  grid-cols-3 ~gap-[1.25rem]\/[1.5rem]\">\n\t\t\t\t\t\t\t<div class=\"icon-item flex gap-[0.75rem] md:items-center max-md:flex-col\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon-image h-[3.5rem] w-[3.5rem] shrink-0\">\n\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/reorder-reorder-arrow-move-arrange.svg?w=56\"  loading=\"lazy\" alt=\"reorder&#8211;reorder-arrow-move-arrange\">\n\t\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex-1 h-fit md:justify-center flex flex-col gap-[0.75rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<small class=\"text-black-60\">Industria<\/small>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"sm\">M\u00e9dica<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"icon-item flex gap-[0.75rem] md:items-center max-md:flex-col\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon-image h-[3.5rem] w-[3.5rem] shrink-0\">\n\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/update.svg?w=56\"  loading=\"lazy\" alt=\"update\">\n\t\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex-1 h-fit md:justify-center flex flex-col gap-[0.75rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<small class=\"text-black-60\">Aplicaci\u00f3n<\/small>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"sm\">Etiquetado<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"icon-item flex gap-[0.75rem] md:items-center max-md:flex-col\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon-image h-[3.5rem] w-[3.5rem] shrink-0\">\n\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/traffic.svg?w=56\"  loading=\"lazy\" alt=\"traffic\">\n\t\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex-1 h-fit md:justify-center flex flex-col gap-[0.75rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<small class=\"text-black-60\">Soluci\u00f3n rob\u00f3tica<\/small>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"sm\">i4L<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/section>\n\n<h2 id=\"h-meeting-the-demands-of-modern-clinical-labs-with-precision-automation\" class=\"wp-block-heading has-large-font-size\">Satisfacer las demandas de los laboratorios cl\u00ednicos modernos con automatizaci\u00f3n de precisi\u00f3n<\/h2>\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/www.werfen.com\/it\/it\" target=\"_blank\" rel=\"noreferrer noopener\">Werfen<\/a>, l\u00edder mundial en diagn\u00f3stico in vitro, se enfrent\u00f3 a un aumento en la demanda de materiales de control y calibraci\u00f3n, especialmente de los laboratorios de toxicolog\u00eda que requieren reactivos sensibles manipulados con el m\u00e1ximo cuidado. Los sistemas de etiquetado tradicionales no pod\u00edan garantizar la manipulaci\u00f3n vertical necesaria para preservar la calidad de los reactivos, ni pod\u00edan mantener la velocidad de producci\u00f3n requerida. Para resolver estos desaf\u00edos, Werfen se asoci\u00f3 con OMRON, <a href=\"https:\/\/macco-srl.it\/en\/\" target=\"_blank\" rel=\"noreferrer noopener\">MACCO<\/a> y Marini Pandolfi para implementar una soluci\u00f3n avanzada de etiquetado automatizado de viales.  <\/p>\n\n<p class=\"has-medium-font-size wp-block-paragraph\">El resultado: un sistema de vanguardia impulsado por <a href=\"https:\/\/robotics.omron.com\/es\/products\/industrial-robots\/scara\/i4l\/\" target=\"_blank\" rel=\"noreferrer noopener\">robots SCARA i4L<\/a> de OMRON y <a href=\"https:\/\/automation.omron.com\/en\/us\/products\/family\/FHV7\" target=\"_blank\" rel=\"noreferrer noopener\">c\u00e1maras de visi\u00f3n inteligente FHV7<\/a>, dise\u00f1ado para mantener los viales en posici\u00f3n vertical durante todo el proceso de llenado y etiquetado. Este m\u00e9todo preciso protege la calidad de los reactivos, garantiza la trazabilidad total y garantiza una manipulaci\u00f3n segura, al tiempo que ofrece hasta 1000 tubos etiquetados por hora y reduce los tiempos de ciclo en un 30%. <\/p>\n\n<p class=\"has-medium-font-size wp-block-paragraph\">La rob\u00f3tica y la tecnolog\u00eda de visi\u00f3n de OMRON permiten una colocaci\u00f3n precisa de c\u00f3digos de barras y etiquetas, mientras que el control de calidad en tiempo real detecta y rechaza autom\u00e1ticamente los tubos no conformes, minimizando el desperdicio y maximizando la fiabilidad. La tecnolog\u00eda de simulaci\u00f3n virtual permiti\u00f3 a Werfen predecir el rendimiento del sistema antes de la instalaci\u00f3n, optimizando la fiabilidad y reduciendo los costes de implementaci\u00f3n. <\/p>\n\n<h4 id=\"h-watch-werfen-s-story\" class=\"wp-block-heading\" style=\"font-size:26px\"><strong>Vea la historia de Werfen:<\/strong><\/h4>\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Werfen Vertical Labelling Achieves 1000 Tubes Per Hour and 30% Faster Automation | OMRON Robotics\" src=\"https:\/\/player.vimeo.com\/video\/1085117389?dnt=1&amp;app_id=122963\" width=\"500\" height=\"281\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe>\n<\/div><\/figure>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50 is-style-fill\"><a class=\"wp-block-button__link has-medium-font-size has-custom-font-size wp-element-button\" href=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Werfen-and-OMRON-Case-Study.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Descargue la historia completa<\/a><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\">Descargar en: <a href=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Werfen-and-OMRON-Case-Study_Italian.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">italiano<\/a> | <a href=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Werfen-and-OMRON-Case-Study_German-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">alem\u00e1n<\/a> | <a href=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Werfen-and-OMRON-Case-Study_Spanish-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">espa\u00f1ol<\/a> | <a href=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Werfen-and-OMRON-Case-Study_French.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">franc\u00e9s<\/a> | <a href=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Werfen-and-OMRON-Case-Study_Polish.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">polaco<\/a> | <a href=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Werfen-and-OMRON-Case-Study_Turkish-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">turco<\/a><\/p>\n\t\t<section class=\"post-pull-quote\">\n        \n\t\t\n\t\t<div class=\"quote-container ~py-[1.5rem]\/[36px]\">\n\t\t\t<div class=\"quote relative\">\n                <svg class=\"absolute ~top-[0.25rem]\/[0.5625rem] left-0 h-[1.5rem] w-[1.5rem]\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M17.76 10.0799V9.1199C17.76 7.2671 18.8366 5.7599 20.16 5.7599H20.64V2.3999H20.16C16.4544 2.3999 13.44 5.4143 13.44 9.1199V19.6799H23.04V10.0799H17.76ZM5.27996 10.0799V9.1199C5.27996 7.2671 6.3566 5.7599 7.67996 5.7599H8.15996V2.3999H7.67996C3.97436 2.3999 0.959961 5.4143 0.959961 9.1199V19.6799H10.56V10.0799H5.27996Z\" fill=\"#6AFF96\"\/>\n                <\/svg>\n\n                                \n                <h4 class=\"h4 quote-text\"><span class=\"~w-[5.875rem]\/[8.75rem] h-[2.5rem] shrink-0\"><\/span><span class=\"word\">\u201cLa&nbsp;<\/span><span class=\"word\">soluci\u00f3n&nbsp;<\/span><span class=\"word\">propuesta&nbsp;<\/span><span class=\"word\">por&nbsp;<\/span><span class=\"word\">MACCO&nbsp;<\/span><span class=\"word\">fue&nbsp;<\/span><span class=\"word\">un&nbsp;<\/span><span class=\"word\">gran&nbsp;<\/span><span class=\"word\">avance&nbsp;<\/span><span class=\"word\">para&nbsp;<\/span><span class=\"word\">nosotros&nbsp;<\/span><span class=\"word\">porque,&nbsp;<\/span><span class=\"word\">con&nbsp;<\/span><span class=\"word\">el&nbsp;<\/span><span class=\"word\">sistema&nbsp;<\/span><span class=\"word\">rob\u00f3tico&nbsp;<\/span><span class=\"word\">y&nbsp;<\/span><span class=\"word\">de&nbsp;<\/span><span class=\"word\">visi\u00f3n&nbsp;<\/span><span class=\"word\">de&nbsp;<\/span><span class=\"word\">OMRON,&nbsp;<\/span><span class=\"word\">podemos&nbsp;<\/span><span class=\"word\">manipular&nbsp;<\/span><span class=\"word\">el&nbsp;<\/span><span class=\"word\">producto&nbsp;<\/span><span class=\"word\">verticalmente&nbsp;<\/span><span class=\"word\">y&nbsp;<\/span><span class=\"word\">controlar&nbsp;<\/span><span class=\"word\">su&nbsp;<\/span><span class=\"word\">calidad&nbsp;<\/span><span class=\"word\">hasta&nbsp;<\/span><span class=\"word\">el&nbsp;<\/span><span class=\"word\">final.\u201d&nbsp;<\/span><span class=\"word\">\u2014&nbsp;<\/span><span class=\"word\">Bruno&nbsp;<\/span><span class=\"word\">Costantini,&nbsp;<\/span><span class=\"word\">director&nbsp;<\/span><span class=\"word\">de&nbsp;<\/span><span class=\"word\">planta,&nbsp;<\/span><span class=\"word\">Werfen&nbsp;<\/span><\/h4>\n            <\/div>\n\t\t<\/div>\n\t<\/section>\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-autoplay=\"true\" data-delay=\"4\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1063\" alt=\"Etiquetado automatizado de viales con robot SCARA de OMRON en las instalaciones de diagn\u00f3stico de Werfen\" class=\"wp-block-jetpack-slideshow_image wp-image-153979\" data-id=\"153979\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Operators-Cell.jpg?w=1024\" srcset=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Operators-Cell.jpg 1920w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Operators-Cell.jpg?resize=300,166 300w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Operators-Cell.jpg?resize=768,425 768w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Operators-Cell.jpg?resize=1024,567 1024w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Operators-Cell.jpg?resize=1536,850 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1078\" alt=\"Manipulaci\u00f3n vertical de viales para el etiquetado de reactivos de alta calidad en el diagn\u00f3stico cl\u00ednico\" class=\"wp-block-jetpack-slideshow_image wp-image-153981\" data-id=\"153981\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-Labelling-Robot.jpg?w=1024\" srcset=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-Labelling-Robot.jpg 1920w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-Labelling-Robot.jpg?resize=300,168 300w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-Labelling-Robot.jpg?resize=768,431 768w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-Labelling-Robot.jpg?resize=1024,575 1024w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-Labelling-Robot.jpg?resize=1536,862 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1021\" alt=\"Sistema de visi\u00f3n inteligente FHV7 de OMRON que garantiza la colocaci\u00f3n precisa de c\u00f3digos de barras en el etiquetado automatizado de viales\" class=\"wp-block-jetpack-slideshow_image wp-image-153983\" data-id=\"153983\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-Labelling.jpg?w=1024\" srcset=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-Labelling.jpg 1920w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-Labelling.jpg?resize=300,160 300w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-Labelling.jpg?resize=768,408 768w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-Labelling.jpg?resize=1024,545 1024w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-Labelling.jpg?resize=1536,817 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1082\" alt=\"Proceso de etiquetado automatizado de viales impulsado por simulaci\u00f3n para mejorar la fiabilidad y la eficiencia\" class=\"wp-block-jetpack-slideshow_image wp-image-153985\" data-id=\"153985\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-HMI-i4L-Robot.jpg?w=1024\" srcset=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-HMI-i4L-Robot.jpg 1920w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-HMI-i4L-Robot.jpg?resize=300,169 300w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-HMI-i4L-Robot.jpg?resize=768,433 768w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-HMI-i4L-Robot.jpg?resize=1024,577 1024w, https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Vial-HMI-i4L-Robot.jpg?resize=1536,866 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n<h3 id=\"h-results-at-a-glance\" class=\"wp-block-heading has-large-font-size\">Resumen de los resultados:<\/h3>\n\n<ul class=\"wp-block-list\">\n<li class=\"has-medium-font-size\">Hasta 1000 viales etiquetados por hora<\/li>\n\n\n\n<li class=\"has-medium-font-size\">Reducci\u00f3n del 30% en el tiempo de ciclo en comparaci\u00f3n con los procesos manuales<\/li>\n\n\n\n<li class=\"has-medium-font-size\">Control de calidad mejorado con sistemas de visi\u00f3n inteligente<\/li>\n\n\n\n<li class=\"has-medium-font-size\">Desperdicio minimizado mediante el rechazo en tiempo real de tubos no conformes<\/li>\n\n\n\n<li class=\"has-medium-font-size\">El dise\u00f1o impulsado por simulaci\u00f3n mejor\u00f3 la fiabilidad y redujo los costes de implementaci\u00f3n<\/li>\n<\/ul>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 id=\"h-tailored-automation-for-diagnostics-manufacturing\" class=\"wp-block-heading has-large-font-size\">Automatizaci\u00f3n a medida para la fabricaci\u00f3n de diagn\u00f3sticos<\/h3>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Con las soluciones de etiquetado automatizado de viales de OMRON, los fabricantes como Werfen pueden ampliar r\u00e1pidamente la producci\u00f3n, mantener los m\u00e1s altos est\u00e1ndares de calidad y cumplir con los estrictos requisitos de la industria de diagn\u00f3stico. Nuestra experiencia en automatizaci\u00f3n industrial le permite aumentar la productividad, garantizar la seguridad y preparar sus operaciones para el futuro. <\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">\u00bfListo para transformar su proceso de producci\u00f3n? P\u00f3ngase en contacto con nosotros hoy mismo para ver c\u00f3mo OMRON puede dise\u00f1ar una soluci\u00f3n automatizada adaptada a su flujo de trabajo. <\/p>\n<\/div>\n<\/div>\n<section class=\"post-footer-subscribe\">\n\t\n\t<div class=\"flex flex-col ~gap-[2.25rem]\/[6rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<a class=\"post-back\" href=\"https:\/\/robotics.omron.com\/case-studies\/\" target=\"_self\">\n\t\t\t\t<svg width=\"13\" height=\"13\" viewbox=\"0 0 13 13\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t<path d=\"M4.44255 10.375L1.15088 6.94618L4.44254 3.51736\" stroke=\"#262626\" stroke-opacity=\"0.6\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t\t<path d=\"M11.9859 0.500098L11.9859 5.84905C11.9859 6.45472 11.4943 6.94627 10.8887 6.94627L1.01367 6.94627\" stroke=\"#262626\" stroke-opacity=\"0.6\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t<\/svg>\n\n\t\t\t\t<p>Volver a casos de estudio<\/p>\n\t\t\t<\/a>\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"form\">\n\t\t\t\t<div class=\"form-inner\">\n\t\t\t\t\t<div class=\"flex gap-[0.75rem]\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"w-[1.5625rem] h-[1.5625rem] object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/png\/rss.png\" width=\"25\" height=\"25\" loading=\"lazy\" alt=\"rss\">\n\t\t\t\t\t\t<p class=\"lg text-white\">Reservar una consulta<\/p>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"form-container blog-footer-form\" data-region=\"na2\" data-form-id=\"7065ef92-974f-4347-bdb3-2caee74b6da1\" data-portal-id=\"47882041\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"form-graphic\">\n\t\t\t\t\t<img decoding=\"async\" class=\"object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/svg\/form-robot.svg\" width=\"218\" height=\"214\" loading=\"lazy\" alt=\"form robot background\">\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/section>\n\n<section class=\"content-rich-text-rc-end \">\n\t\n\t\t\n\t<div class=\"inner ~pt-[7.25rem]\/[10.25rem] sb-xxl\">\n\t\t<div class=\"container\">\n\t\t\t<div class=\"content-outer\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<\/section>\n<section class=\"resource-three-across-featured bg-beige\">\n\t\n\t\t\n\t<div class=\"container\">\n\t\t<div class=\"st-xl sb-xxl\">\n\t\t\t<div class=\"flex flex-col ~gap-[2.25rem]\/[3rem]\">\n\t\t\t\t<div class=\"flex max-md:flex-col gap-[1.5rem] justify-between md:items-end\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex-1 max-w-[39.25rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t        <h3 class=\"main-title  flex flex-wrap\"><span class=\"outer-word\"><span class=\"inner-word\">Informaci\u00f3n&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">relacionada&nbsp;<\/span><\/span><\/h3>\n    \t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t<a class=\"btn filled blue shrink-0  has-arrow\" type=\"button\" href=\"https:\/\/robotics.omron.com\/es\/blog\/\" target=\"_self\">\n\t\t\t\t\t\t\t<svg width=\"13\" height=\"13\" viewbox=\"0 0 13 13\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t<path d=\"M8.55697 10.375L11.8486 6.94618L8.55697 3.51736\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t\t<path d=\"M1.01411 0.500006L1.0141 5.84896C1.0141 6.45463 1.50566 6.94618 2.11133 6.94618L11.9863 6.94618\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t<\/svg>\n\t\t\t\n\t\t\t<p>Ver toda la informaci\u00f3n<\/p>\n\t\t<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"items\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n                                                                                        \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                            \n\t\t\t\t\t\t\t<a class=\"blog-card resource-three-feature\" href=\"https:\/\/robotics.omron.com\/es\/case-studies\/robotic-palletizer-sanofi-omron\/\" >\n\t<div class=\"blog-card-inner\">\n\t\t<div class=\"flex flex-col gap-[0.75rem]\">\n\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"blog-card-image h-[11.5rem] rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2024\/09\/Robotic-palletizer-stacking-boxes-on-a-pallet_crop.jpg?w=1024\"  loading=\"lazy\" alt=\"Robotic palletizer stacking boxes on a pallet_crop\">\n\t\n\n\t\t\t\n\t\t\t<div class=\"flex justify-between gap-[1.5rem]\">\n\t\t\t\t\t<div class=\"flex gap-[0.5rem] items-center \">\n\t\t<div class=\"w-[0.5rem] h-[0.5rem] shrink-0 bg-green\"><\/div>\n\t\t<small class=\"text-black-60\">Caso pr\u00e1ctico<\/small>\n\t<\/div>\n\t\t\t\t<small class=\"text-black-60\">13\/9\/2024<\/small>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<p class=\"lg\">Sanofi automatiza el envasado de final de l\u00ednea para 1000 millones de dosis de vacunas<\/p>\n\t<\/div>\n<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n                                                                                        \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                            \n\t\t\t\t\t\t\t<a class=\"blog-card resource-three-feature\" href=\"https:\/\/robotics.omron.com\/es\/case-studies\/material-handling-automation-hipra-omron\/\" >\n\t<div class=\"blog-card-inner\">\n\t\t<div class=\"flex flex-col gap-[0.75rem]\">\n\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"blog-card-image h-[11.5rem] rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/08\/OMRON-LD-90-AMRs-in-Action.jpg?w=1024\"  loading=\"lazy\" alt=\"OMRON LD-90 AMRs in Action\">\n\t\n\n\t\t\t\n\t\t\t<div class=\"flex justify-between gap-[1.5rem]\">\n\t\t\t\t\t<div class=\"flex gap-[0.5rem] items-center \">\n\t\t<div class=\"w-[0.5rem] h-[0.5rem] shrink-0 bg-green\"><\/div>\n\t\t<small class=\"text-black-60\">Caso pr\u00e1ctico<\/small>\n\t<\/div>\n\t\t\t\t<small class=\"text-black-60\">1\/8\/2024<\/small>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<p class=\"lg\">HIPRA automatiza 700 transferencias diarias de vacunas con AMR<\/p>\n\t<\/div>\n<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n                                                                                        \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                            \n\t\t\t\t\t\t\t<a class=\"blog-card resource-three-feature\" href=\"https:\/\/robotics.omron.com\/es\/case-studies\/automating-end-of-line-bottle-feeding-with-high-speed-circular-tracking\/\" >\n\t<div class=\"blog-card-inner\">\n\t\t<div class=\"flex flex-col gap-[0.75rem]\">\n\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"blog-card-image h-[11.5rem] rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2026\/03\/Robotic-pick-and-place-unit-transferring-bottles-into-conveyor-lanes.webp?w=1024\"  loading=\"lazy\" alt=\"Unidad rob\u00f3tica de pick-and-place transfiriendo botellas a carriles de transportador\">\n\t\n\n\t\t\t\n\t\t\t<div class=\"flex justify-between gap-[1.5rem]\">\n\t\t\t\t\t<div class=\"flex gap-[0.5rem] items-center \">\n\t\t<div class=\"w-[0.5rem] h-[0.5rem] shrink-0 bg-green\"><\/div>\n\t\t<small class=\"text-black-60\">Caso pr\u00e1ctico<\/small>\n\t<\/div>\n\t\t\t\t<small class=\"text-black-60\">19\/3\/2026<\/small>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<p class=\"lg\">Automatizaci\u00f3n de la alimentaci\u00f3n de botellas al final de l\u00ednea con circular tracking de alta velocidad<\/p>\n\t<\/div>\n<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n","protected":false},"excerpt":{"rendered":"<p>Werfen aument\u00f3 la velocidad de etiquetado en un 30% hasta 1000 tubos\/hora con el etiquetado automatizado de viales y el control de calidad de visi\u00f3n inteligente de OMRON, lo que garantiza una calidad superior de los reactivos y una eficiencia de producci\u00f3n.<\/p>\n","protected":false},"featured_media":164202,"template":"","meta":{"_acf_changed":false},"case-study-category":[812,824,815,817,819,829],"class_list":["post-181687","case-study","type-case-study","status-publish","has-post-thumbnail","hentry","case-study-category-robots-industriales","case-study-category-scara","case-study-category-industrias","case-study-category-medica","case-study-category-aplicaciones","case-study-category-procesando"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Etiquetado autom\u00e1tico aumenta producci\u00f3n Werfen un 30%<\/title>\n<meta name=\"description\" content=\"Werfen: etiquetado autom\u00e1tico OMRON a 1000 tubos\/hora.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo etiquetar werfen 1000 viales por hora con automatizaci\u00f3n?\" \/>\n<meta property=\"og:description\" content=\"Werfen: etiquetado autom\u00e1tico OMRON a 1000 tubos\/hora.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/\" \/>\n<meta property=\"og:site_name\" content=\"OMRON Robotics\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-23T22:59:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Operators-Cell.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1063\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/case-studies\\\/automated-vial-labelling-omron-werfen\\\/\",\"url\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/case-studies\\\/automated-vial-labelling-omron-werfen\\\/\",\"name\":\"Etiquetado autom\u00e1tico aumenta producci\u00f3n Werfen un 30%\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/case-studies\\\/automated-vial-labelling-omron-werfen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/case-studies\\\/automated-vial-labelling-omron-werfen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/robotics.omron.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Macco-Werfen-Operators-Cell.jpg\",\"datePublished\":\"2025-01-15T04:18:00+00:00\",\"dateModified\":\"2026-07-23T22:59:51+00:00\",\"description\":\"Werfen: etiquetado autom\u00e1tico OMRON a 1000 tubos\\\/hora.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/case-studies\\\/automated-vial-labelling-omron-werfen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/robotics.omron.com\\\/es\\\/case-studies\\\/automated-vial-labelling-omron-werfen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/case-studies\\\/automated-vial-labelling-omron-werfen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/robotics.omron.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Macco-Werfen-Operators-Cell.jpg\",\"contentUrl\":\"https:\\\/\\\/robotics.omron.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Macco-Werfen-Operators-Cell.jpg\",\"width\":1920,\"height\":1063,\"caption\":\"Etiquetado automatizado de viales con robot SCARA de OMRON en las instalaciones de diagn\u00f3stico de Werfen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/case-studies\\\/automated-vial-labelling-omron-werfen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo etiquetar werfen 1000 viales por hora con automatizaci\u00f3n?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/\",\"name\":\"OMRON Robotics\",\"description\":\"Transforming Manufacturing Through Robotics\",\"publisher\":{\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/#organization\",\"name\":\"OMRON Robotics\",\"url\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/robotics.omron.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/OMRON_Logo.svg?w=1024\",\"contentUrl\":\"https:\\\/\\\/robotics.omron.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/OMRON_Logo.svg?w=1024\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"OMRON Robotics\"},\"image\":{\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/omron-robotics\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@OmronRoboticsAmericas\\\/featured\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Etiquetado autom\u00e1tico aumenta producci\u00f3n Werfen un 30%","description":"Werfen: etiquetado autom\u00e1tico OMRON a 1000 tubos\/hora.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo etiquetar werfen 1000 viales por hora con automatizaci\u00f3n?","og_description":"Werfen: etiquetado autom\u00e1tico OMRON a 1000 tubos\/hora.","og_url":"https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/","og_site_name":"OMRON Robotics","article_modified_time":"2026-07-23T22:59:51+00:00","og_image":[{"width":1920,"height":1063,"url":"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Operators-Cell.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/","url":"https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/","name":"Etiquetado autom\u00e1tico aumenta producci\u00f3n Werfen un 30%","isPartOf":{"@id":"https:\/\/robotics.omron.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/#primaryimage"},"image":{"@id":"https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/#primaryimage"},"thumbnailUrl":"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Operators-Cell.jpg","datePublished":"2025-01-15T04:18:00+00:00","dateModified":"2026-07-23T22:59:51+00:00","description":"Werfen: etiquetado autom\u00e1tico OMRON a 1000 tubos\/hora.","breadcrumb":{"@id":"https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/#primaryimage","url":"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Operators-Cell.jpg","contentUrl":"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Operators-Cell.jpg","width":1920,"height":1063,"caption":"Etiquetado automatizado de viales con robot SCARA de OMRON en las instalaciones de diagn\u00f3stico de Werfen"},{"@type":"BreadcrumbList","@id":"https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/robotics.omron.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo etiquetar werfen 1000 viales por hora con automatizaci\u00f3n?"}]},{"@type":"WebSite","@id":"https:\/\/robotics.omron.com\/es\/#website","url":"https:\/\/robotics.omron.com\/es\/","name":"OMRON Robotics","description":"Transforming Manufacturing Through Robotics","publisher":{"@id":"https:\/\/robotics.omron.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/robotics.omron.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/robotics.omron.com\/es\/#organization","name":"OMRON Robotics","url":"https:\/\/robotics.omron.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/robotics.omron.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/08\/OMRON_Logo.svg?w=1024","contentUrl":"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/08\/OMRON_Logo.svg?w=1024","width":"1024","height":"1024","caption":"OMRON Robotics"},"image":{"@id":"https:\/\/robotics.omron.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/showcase\/omron-robotics\/","https:\/\/www.youtube.com\/@OmronRoboticsAmericas\/featured"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/robotics.omron.com\/es\/wp-json\/wp\/v2\/case-study\/181687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robotics.omron.com\/es\/wp-json\/wp\/v2\/case-study"}],"about":[{"href":"https:\/\/robotics.omron.com\/es\/wp-json\/wp\/v2\/types\/case-study"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/robotics.omron.com\/es\/wp-json\/wp\/v2\/media\/164202"}],"wp:attachment":[{"href":"https:\/\/robotics.omron.com\/es\/wp-json\/wp\/v2\/media?parent=181687"}],"wp:term":[{"taxonomy":"case-study-category","embeddable":true,"href":"https:\/\/robotics.omron.com\/es\/wp-json\/wp\/v2\/case-study-category?post=181687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}