{"id":180867,"date":"2025-03-07T08:36:55","date_gmt":"2025-03-07T16:36:55","guid":{"rendered":"https:\/\/robotics.omron.com\/?page_id=180867"},"modified":"2026-08-30T23:21:27","modified_gmt":"2026-08-31T06:21:27","slug":"software","status":"publish","type":"page","link":"https:\/\/robotics.omron.com\/es\/products\/industrial-robots\/software\/","title":{"rendered":"Software ACE"},"content":{"rendered":"<section class=\"hero-image-dark-bg bg-black overflow-hidden\">\n\t\n\t\t\n\t<div class=\"container relative z-[2]\">\n\t\t<div class=\"~pt-[6.25rem]\/[8.875rem] sb-xl\">\n\t\t\t<div class=\"flex ~gap-[3rem]\/[4rem] items-center flex-col\">\n\t\t\t\t<div class=\"~px-[0rem]\/[14.25rem] flex ~gap-[1.25rem]\/[4rem] md:items-end relative z-[2] max-md:flex-col\">\n\t\t\t\t\t<div class=\"flex flex-col gap-[0.75rem] md:flex-1 md:basis-[28.5rem]\">\n\t\t\t\t\t\t\t<div class=\"flex gap-[0.5rem] items-center \">\n\t\t<div class=\"w-[0.5rem] h-[0.5rem] shrink-0 bg-green\"><\/div>\n\t\t<small class=\"text-white-60\">INDUSTRIAL<\/small>\n\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\n\t        <h3 class=\"main-title text-white  flex flex-wrap\"><span class=\"outer-word\"><span class=\"inner-word\">Software&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">ACE&nbsp;<\/span><\/span><\/h3>\n    \t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"para-desc md:flex-1 md:basis-[27rem] text-white\">ACE es la plataforma de software integrada de OMRON para gestionar robots industriales, controles, visi\u00f3n y sistemas de alimentaci\u00f3n.<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"media-container-outer video\">\n\t\t\t\t\t\t\t<div class=\"media-container\">\n\t\t\t\t\t\t\t\t<div class=\"video-box\">\n                                    <div class=\"video-play\">\n                                        <small class=\"text-white uppercase\">Watch<br>now<\/small>\n                                    <\/div>\n\n                                    <div class=\"video-thumbnail\">\n                                        <div class=\"gradient-overlay\"><\/div>\n                                    <\/div>\n\n                                    <div class=\"video-container\" data-video-id=\"1075748274\"><\/div>\n                                <\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"orb-container\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"orb\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/webp\/hero-software-orb.webp\" loading=\"eager\" alt=\"orb background\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"absolute bottom-0 h-auto w-full pointer-events-none z-[1] left-[50%] translate-x-[-50%] scale-y-[-1] min-w-[90rem]\">\n\t\t<div class=\"lottie\" data-json=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/json\/lottie\/green-trail-dark.json\"><\/div>\n\n\t\t<div class=\"h-full w-full absolute top-0 left-0 z-[2]\" style=\"background: linear-gradient(180deg, rgba(38, 38, 38, 0.00) 0%, #262626 100%);\"><\/div>\n\t<\/div>\n<\/section>\n\n\t\t<section class=\"content-big-moment-statement bg-white\">\n\t\t\n\t\t\t\t\n\t\t<div class=\"container relative z-[2]\">\n\t\t\t<div class=\"st-xxl sb-xxl\">\n\t\t\t\t<div class=\"quote ~px-[0rem]\/[14.25rem]\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h5 class=\"quote-text\"><span class=\"~w-[5.875rem]\/[8.75rem] h-[1.25rem] shrink-0\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">El&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">software&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">ACE&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">(entorno&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">de&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">control&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">de&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">automatizaci\u00f3n)&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">es&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">su&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">soluci\u00f3n&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">todo&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">en&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">uno&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">para&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">programar,&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">implementar&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">y&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">gestionar&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">robots&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">industriales.&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">Desde&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">tareas&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">de&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">pick-and-place&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">hasta&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">sistemas&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">multi-robot,&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">ACE&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">agiliza&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">la&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">configuraci\u00f3n&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">con&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">asistentes&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">paso&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">a&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">paso&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">y&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">herramientas&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">de&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">visi\u00f3n&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">avanzadas&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">para&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">la&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">localizaci\u00f3n&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">e&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">inspecci\u00f3n.&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">Su&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">dise\u00f1o&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">f\u00e1cil&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">de&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">usar&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">aumenta&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">la&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">productividad,&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">reduce&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">los&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">errores&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">y&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">permite&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">operaciones&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">eficientes&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">y&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">escalables.&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"word\">&nbsp;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"parallax absolute ~left-[-0.625rem]\/[0rem] ~top-[1.875rem]\/[4.375rem]\">\n\t\t\t\t<img decoding=\"async\" class=\"~w-[25.75rem]\/[39.375rem] ~h-[10rem]\/[17.5rem] object-contain object-left-top opacity-80\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Big_Statement_Industrial-1.svg\" loading=\"lazy\" alt=\"background graphic\">\n\t\t\t<\/div>\n\t\t\t<\/section>\n<section class=\"content-fifty-fifty-image-vertical-tabs bg-beige \">\n\t\n\t\t\n\t<div class=\"container\">\n\t\t<div class=\"st-xl sb-xl\">\n\t\t\t<div class=\"inner flex gap-[7.125rem] max-md:flex-col\">\n\t\t\t\t<div class=\"item-images md:flex-1 md:basis-[42.75rem] max-md:hidden items-center relative flex\">\n\t\t\t\t\t\t\t\t\t\t\t                            <div class=\"item-image\" data-index=\"1\">\n                                \t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/ACE_interface_parallel-robots.jpg?w=1024\"  loading=\"lazy\" alt=\"ACE_interface_parallel-robots\">\n\t\n\n                            <\/div>\n                                                    <div class=\"item-image\" data-index=\"2\">\n                                \t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Industrial_Robot_Simulation.png?w=1024\"  loading=\"lazy\" alt=\"Industrial_Robot_Simulation\">\n\t\n\n                            <\/div>\n                                                    <div class=\"item-image\" data-index=\"3\">\n                                \t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/20210119-080135-001.jpg?w=1024\"  loading=\"lazy\" alt=\"20210119-080135-001\">\n\t\n\n                            <\/div>\n                                                    <div class=\"item-image\" data-index=\"4\">\n                                \t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/3D-Pick-Manager.jpg?w=1024\"  loading=\"lazy\" alt=\"3D Pick Manager\">\n\t\n\n                            <\/div>\n                        \t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"flex flex-col ~gap-[2.25rem]\/[2.9375rem] md:flex-1 md:basis-[34.125rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t        <h3 class=\"main-title  flex flex-wrap\"><span class=\"outer-word\"><span class=\"inner-word\">Ahorre&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">tiempo&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">y&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">agilice&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">las&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">aplicaciones&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">con&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">el&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">software&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">ACE&nbsp;<\/span><\/span><\/h3>\n    \t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item ~pt-[1.25rem]\/[1.5rem] ~pb-[0.625rem]\/[0.75rem] last:pb-0 border-t-[0.0625rem] border-t-gray-2 flex flex-col gap-[0.75rem] cursor-pointer\" data-index=\"1\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-row gap-[1rem]\">\n\t\t\t\t\t\t\t\t\t\t<small class=\"text-[0.75rem] text-black-60 relative top-[0.375rem]\">01<\/small>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"lg\">Interfaz f\u00e1cil de usar<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>ACE 4.0 cuenta con una interfaz basada en asistentes para una calibraci\u00f3n, ense\u00f1anza e implementaci\u00f3n de robots sin problemas.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-inner-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/ACE_interface_parallel-robots.jpg?w=312\"  loading=\"lazy\" alt=\"ACE_interface_parallel-robots\">\n\t\n\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item ~pt-[1.25rem]\/[1.5rem] ~pb-[0.625rem]\/[0.75rem] last:pb-0 border-t-[0.0625rem] border-t-gray-2 flex flex-col gap-[0.75rem] cursor-pointer\" data-index=\"2\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-row gap-[1rem]\">\n\t\t\t\t\t\t\t\t\t\t<small class=\"text-[0.75rem] text-black-60 relative top-[0.375rem]\">02<\/small>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"lg\">Productividad mejorada<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Agilice la configuraci\u00f3n y reduzca los errores con herramientas intuitivas para una prueba de concepto m\u00e1s r\u00e1pida y operaciones eficientes.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-inner-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Industrial_Robot_Simulation.png?w=312\"  loading=\"lazy\" alt=\"Industrial_Robot_Simulation\">\n\t\n\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item ~pt-[1.25rem]\/[1.5rem] ~pb-[0.625rem]\/[0.75rem] last:pb-0 border-t-[0.0625rem] border-t-gray-2 flex flex-col gap-[0.75rem] cursor-pointer\" data-index=\"3\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-row gap-[1rem]\">\n\t\t\t\t\t\t\t\t\t\t<small class=\"text-[0.75rem] text-black-60 relative top-[0.375rem]\">03<\/small>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"lg\">Herramientas de visi\u00f3n avanzadas<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>M\u00e1s de 35 herramientas de visi\u00f3n para la localizaci\u00f3n, la inspecci\u00f3n y la detecci\u00f3n de defectos mejoran el control de calidad y la trazabilidad.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-inner-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/20210119-080135-001.jpg?w=312\"  loading=\"lazy\" alt=\"20210119-080135-001\">\n\t\n\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item ~pt-[1.25rem]\/[1.5rem] ~pb-[0.625rem]\/[0.75rem] last:pb-0 border-t-[0.0625rem] border-t-gray-2 flex flex-col gap-[0.75rem] cursor-pointer\" data-index=\"4\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-row gap-[1rem]\">\n\t\t\t\t\t\t\t\t\t\t<small class=\"text-[0.75rem] text-black-60 relative top-[0.375rem]\">04<\/small>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"lg\">Automatizaci\u00f3n escalable<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Desde pick-and-place hasta sistemas multi-robot, ACE admite soluciones flexibles y escalables para necesidades de automatizaci\u00f3n complejas.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-inner-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/3D-Pick-Manager.jpg?w=312\"  loading=\"lazy\" alt=\"3D Pick Manager\">\n\t\n\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"content-fifty-fifty-image-vertical-tabs bg-beige is-inverted\">\n\t\n\t\t\n\t<div class=\"container\">\n\t\t<div class=\"st-xl sb-xl\">\n\t\t\t<div class=\"inner flex gap-[7.125rem] max-md:flex-col\">\n\t\t\t\t<div class=\"item-images md:flex-1 md:basis-[42.75rem] max-md:hidden items-center relative flex\">\n\t\t\t\t\t\t\t\t\t\t\t                            <div class=\"item-image\" data-index=\"1\">\n                                \t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Screenshot-2025-04-07-104937.png?w=1024\"  loading=\"lazy\" alt=\"Screenshot 2025-04-07 104937\">\n\t\n\n                            <\/div>\n                                                    <div class=\"item-image\" data-index=\"2\">\n                                \t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/20210120-143647-001.jpg?w=1024\"  loading=\"lazy\" alt=\"20210120-143647-001\">\n\t\n\n                            <\/div>\n                                                    <div class=\"item-image\" data-index=\"3\">\n                                \t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/ACE-PackXpert-.jpg?w=1024\"  loading=\"lazy\" alt=\"ACE -PackXpert\">\n\t\n\n                            <\/div>\n                                                    <div class=\"item-image\" data-index=\"4\">\n                                \t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Barcode.png?w=651\"  loading=\"lazy\" alt=\"Barcode\">\n\t\n\n                            <\/div>\n                        \t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"flex flex-col ~gap-[2.25rem]\/[2.9375rem] md:flex-1 md:basis-[34.125rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t        <h3 class=\"main-title  flex flex-wrap\"><span class=\"outer-word\"><span class=\"inner-word\">Potencie&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">sus&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">sistemas&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">rob\u00f3ticos&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">con&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">los&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">m\u00f3dulos&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">de&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">software&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">ACE&nbsp;<\/span><\/span><\/h3>\n    \t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item ~pt-[1.25rem]\/[1.5rem] ~pb-[0.625rem]\/[0.75rem] last:pb-0 border-t-[0.0625rem] border-t-gray-2 flex flex-col gap-[0.75rem] cursor-pointer\" data-index=\"1\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-row gap-[1rem]\">\n\t\t\t\t\t\t\t\t\t\t<small class=\"text-[0.75rem] text-black-60 relative top-[0.375rem]\">01<\/small>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"lg\">Administrador de Aplicaci\u00f3n<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Simplifique el desarrollo de aplicaciones con PackManager y VisionManager para una configuraci\u00f3n guiada y sin scripts de tareas de embalaje y visi\u00f3n.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-inner-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Screenshot-2025-04-07-104937.png?w=312\"  loading=\"lazy\" alt=\"Screenshot 2025-04-07 104937\">\n\t\n\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item ~pt-[1.25rem]\/[1.5rem] ~pb-[0.625rem]\/[0.75rem] last:pb-0 border-t-[0.0625rem] border-t-gray-2 flex flex-col gap-[0.75rem] cursor-pointer\" data-index=\"2\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-row gap-[1rem]\">\n\t\t\t\t\t\t\t\t\t\t<small class=\"text-[0.75rem] text-black-60 relative top-[0.375rem]\">02<\/small>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"lg\">PackManager<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Gu\u00eda paso a paso para configurar l\u00edneas de embalaje escalables, optimizar los recursos y reducir el tiempo de inactividad.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-inner-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/20210120-143647-001.jpg?w=312\"  loading=\"lazy\" alt=\"20210120-143647-001\">\n\t\n\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item ~pt-[1.25rem]\/[1.5rem] ~pb-[0.625rem]\/[0.75rem] last:pb-0 border-t-[0.0625rem] border-t-gray-2 flex flex-col gap-[0.75rem] cursor-pointer\" data-index=\"3\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-row gap-[1rem]\">\n\t\t\t\t\t\t\t\t\t\t<small class=\"text-[0.75rem] text-black-60 relative top-[0.375rem]\">03<\/small>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"lg\">Robot VisionManager<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Potentes algoritmos para el seguimiento de transportadores guiado por visi\u00f3n, la integraci\u00f3n de alimentadores de piezas y las herramientas de inspecci\u00f3n.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-inner-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/ACE-PackXpert-.jpg?w=312\"  loading=\"lazy\" alt=\"ACE -PackXpert\">\n\t\n\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item ~pt-[1.25rem]\/[1.5rem] ~pb-[0.625rem]\/[0.75rem] last:pb-0 border-t-[0.0625rem] border-t-gray-2 flex flex-col gap-[0.75rem] cursor-pointer\" data-index=\"4\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-row gap-[1rem]\">\n\t\t\t\t\t\t\t\t\t\t<small class=\"text-[0.75rem] text-black-60 relative top-[0.375rem]\">04<\/small>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"lg\">Aspectos destacados de la herramienta de visi\u00f3n<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Incluye lectura de c\u00f3digos de barras\/QR, coincidencia de formas, detecci\u00f3n de defectos y procesamiento de im\u00e1genes complejo para la fabricaci\u00f3n de precisi\u00f3n.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-inner-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-cover rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Barcode.png?w=312\"  loading=\"lazy\" alt=\"Barcode\">\n\t\n\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"content-cards-icon-hover bg-beige overflow-x-clip overflow-y-visible\">\n\t\n\t\t\n\t<div class=\"relative z-[2] overflow-hidden\">\n\t\t<div class=\"container\">\n\t\t\t<div class=\"st-xl sb-xxl\">\n\t\t\t\t<div class=\"flex flex-col ~gap-[2.25rem]\/[3rem]\">\n\t\t\t\t\t<div class=\"flex flex-col ~gap-[1.25rem]\/[1.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"w-full md:max-w-[55.5rem] relative\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t        <h3 class=\"main-title  flex flex-wrap\">\t<div class=\"flex gap-[0.5rem] items-center shrink-0 align-top h-fit relative pt-[0.75rem] tracking-[normal] max-sm:w-full pb-[0.75rem]\">\n\t\t<div class=\"w-[0.5rem] h-[0.5rem] shrink-0 bg-green\"><\/div>\n\t\t<small class=\"text-black-60\">CARACTER\u00cdSTICAS<\/small>\n\t<\/div>\n<span class=\"max-sm:hidden w-[5rem]\"><\/span><span class=\"outer-word\"><span class=\"inner-word\">Agilice&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">sus&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">operaciones&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">con&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">las&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">potentes&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">herramientas&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">de&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">ACE&nbsp;<\/span><\/span><\/h3>\n    \t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n                                                    <div class=\"flex flex-wrap ~gap-[1.25rem]\/[1.5rem]\">\n                                \t\t\t\n\t\t\t<a class=\"btn filled blue  has-arrow\" type=\"button\" href=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/06\/ACE-4.0-Leaflet.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<svg width=\"13\" height=\"13\" viewbox=\"0 0 13 13\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t<path d=\"M8.55697 10.375L11.8486 6.94618L8.55697 3.51736\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t\t<path d=\"M1.01411 0.500006L1.0141 5.84896C1.0141 6.45463 1.50566 6.94618 2.11133 6.94618L11.9863 6.94618\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t<\/svg>\n\t\t\t\n\t\t\t<p>Descargar folleto<\/p>\n\t\t<\/a>\n\t\n                                                            <\/div>\n                        \t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid grid-cols-1 sm:grid-cols-2 lg:grid-cols-3 xl:grid-cols-4 ~gap-[1.25rem]\/[1.5rem]\">\n\t\t\t\t\t\t\t                                \n                                                                                                \n                                \n\t\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col ~gap-[1.25rem]\/[1.5rem] h-full relative z-[2] overflow-hidden\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"flex justify-between ~gap-[1.25rem]\/[1.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"h-[3.5rem] w-[3.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Intuitive-Programming.png?w=56\"  loading=\"lazy\" alt=\"Intuitive Programming\">\n\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<small class=\"text-[0.75rem] text-white\">01<\/small>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-title\">\n                                                                                                            <h6 class=\"item-title text-white\">Programaci\u00f3n intuitiva<\/h6>\n                                                    \n                                                                                                    <\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"item-desc\">Programe e implemente aplicaciones f\u00e1cilmente con la interfaz basada en asistentes de ACE, ideal para operaciones de pick &amp; place o de seguimiento de cintas transportadoras multi-robot.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"orb absolute pointer-events-none top-0 left-0 z-[1] opacity-0 w-[37.5rem] h-[37.5rem]\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain opacity-40\" loading=\"lazy\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/webp\/orb-white.webp\" alt=\"moving orb\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                \n                                                                                                \n                                \n\t\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col ~gap-[1.25rem]\/[1.5rem] h-full relative z-[2] overflow-hidden\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"flex justify-between ~gap-[1.25rem]\/[1.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"h-[3.5rem] w-[3.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/3D-Visualization.png?w=56\"  loading=\"lazy\" alt=\"3D Visualization\">\n\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<small class=\"text-[0.75rem] text-white\">02<\/small>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-title\">\n                                                                                                            <h6 class=\"item-title text-white\">Visualizaci\u00f3n y emulaci\u00f3n 3D<\/h6>\n                                                    \n                                                                                                    <\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"item-desc\">Cree pruebas de concepto m\u00e1s r\u00e1pido con la emulaci\u00f3n r\u00e1pida y las herramientas de visualizaci\u00f3n 3D de ACE, lo que reduce el tiempo de configuraci\u00f3n y mejora la precisi\u00f3n.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"orb absolute pointer-events-none top-0 left-0 z-[1] opacity-0 w-[37.5rem] h-[37.5rem]\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain opacity-40\" loading=\"lazy\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/webp\/orb-white.webp\" alt=\"moving orb\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"spacer max-xl:hidden\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"spacer max-xl:hidden\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                \n                                                                                                \n                                \n\t\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col ~gap-[1.25rem]\/[1.5rem] h-full relative z-[2] overflow-hidden\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"flex justify-between ~gap-[1.25rem]\/[1.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"h-[3.5rem] w-[3.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Advanced-Vision-Tools.png?w=56\"  loading=\"lazy\" alt=\"Advanced Vision Tools\">\n\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<small class=\"text-[0.75rem] text-white\">03<\/small>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-title\">\n                                                                                                            <h6 class=\"item-title text-white\">Herramientas de visi\u00f3n avanzadas<\/h6>\n                                                    \n                                                                                                    <\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"item-desc\">Aproveche m\u00e1s de 35 herramientas de visi\u00f3n para la inspecci\u00f3n, la localizaci\u00f3n y la detecci\u00f3n de defectos, lo que garantiza la precisi\u00f3n y la calidad en cada proceso.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"orb absolute pointer-events-none top-0 left-0 z-[1] opacity-0 w-[37.5rem] h-[37.5rem]\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain opacity-40\" loading=\"lazy\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/webp\/orb-white.webp\" alt=\"moving orb\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                \n                                                                                                \n                                \n\t\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col ~gap-[1.25rem]\/[1.5rem] h-full relative z-[2] overflow-hidden\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"flex justify-between ~gap-[1.25rem]\/[1.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"h-[3.5rem] w-[3.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Flexible-Automation.png?w=56\"  loading=\"lazy\" alt=\"Flexible Automation\">\n\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<small class=\"text-[0.75rem] text-white\">04<\/small>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-title\">\n                                                                                                            <h6 class=\"item-title text-white\">Automatizaci\u00f3n flexible<\/h6>\n                                                    \n                                                                                                    <\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"item-desc\">Agilice los cambios con Recipe Manager, que gestiona una gama de variaciones de productos para optimizar los flujos de trabajo de fabricaci\u00f3n flexibles.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"orb absolute pointer-events-none top-0 left-0 z-[1] opacity-0 w-[37.5rem] h-[37.5rem]\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain opacity-40\" loading=\"lazy\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/webp\/orb-white.webp\" alt=\"moving orb\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                \n                                                                                                \n                                \n\t\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col ~gap-[1.25rem]\/[1.5rem] h-full relative z-[2] overflow-hidden\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"flex justify-between ~gap-[1.25rem]\/[1.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"h-[3.5rem] w-[3.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Packaging.png?w=56\"  loading=\"lazy\" alt=\"Packaging\">\n\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<small class=\"text-[0.75rem] text-white\">05<\/small>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-title\">\n                                                                                                            <h6 class=\"item-title text-white\">PackManager para embalaje<\/h6>\n                                                    \n                                                                                                    <\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"item-desc\">Dise\u00f1e f\u00e1cilmente l\u00edneas de embalaje escalables con una gu\u00eda paso a paso, desde la integraci\u00f3n hasta la implementaci\u00f3n, sin necesidad de scripts.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"orb absolute pointer-events-none top-0 left-0 z-[1] opacity-0 w-[37.5rem] h-[37.5rem]\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain opacity-40\" loading=\"lazy\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/webp\/orb-white.webp\" alt=\"moving orb\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                \n                                                                                                \n                                \n\t\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col ~gap-[1.25rem]\/[1.5rem] h-full relative z-[2] overflow-hidden\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"flex justify-between ~gap-[1.25rem]\/[1.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"h-[3.5rem] w-[3.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Data-viz.png?w=56\"  loading=\"lazy\" alt=\"Data viz\">\n\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<small class=\"text-[0.75rem] text-white\">06<\/small>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-title\">\n                                                                                                            <h6 class=\"item-title text-white\">Visualizaci\u00f3n de datos mejorada<\/h6>\n                                                    \n                                                                                                    <\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"item-desc\">La interfaz de ACE 4.0 ofrece una potente visualizaci\u00f3n de datos, soporte multiinstancia y atajos de teclado para un desarrollo de proyectos m\u00e1s r\u00e1pido.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"orb absolute pointer-events-none top-0 left-0 z-[1] opacity-0 w-[37.5rem] h-[37.5rem]\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain opacity-40\" loading=\"lazy\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/webp\/orb-white.webp\" alt=\"moving orb\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"parallax absolute ~right-[-12rem]\/[3rem] ~top-[0rem]\/[2.5rem] pointer-events-none\">\n\t\t\t<img decoding=\"async\" class=\"~w-[22.875rem]\/[25rem] max-h-[37.5rem] h-auto object-contain object-right-top opacity-80\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Quattro-Technical-Drawing-2.svg\" loading=\"lazy\" alt=\"background graphic\">\n\t\t<\/div>\n\t<\/section>\n<section class=\"content-full-width-image-with-text-overlay bg-pitch-black\">\n\t\n\t<div class=\"container relative z-[2]\">\n\t\t<div class=\"~pt-[5rem]\/[21.875rem] ~pb-[1.5rem]\/[3.125rem]\">\n\t\t\t<div class=\"h-full w-full flex items-end justify-end max-sm:min-h-[auto] ~min-h-[41.875rem]\/[47.625rem]\">\n\t\t\t\t<div class=\"flex flex-col ~gap-[1.25rem]\/[1.5rem] max-w-[48.375rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t        <h3 class=\"main-title text-white  flex flex-wrap\">\t<div class=\"flex gap-[0.5rem] items-center shrink-0 align-top h-fit relative pt-[0.75rem] tracking-[normal] max-sm:w-full pb-[0.75rem]\">\n\t\t<div class=\"w-[0.5rem] h-[0.5rem] shrink-0 bg-green\"><\/div>\n\t\t<small class=\"text-white-60\">ESTUDIO DE CASO<\/small>\n\t<\/div>\n<span class=\"max-sm:hidden w-[5rem]\"><\/span><span class=\"outer-word\"><span class=\"inner-word\">Vea&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">c\u00f3mo&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">Trelleborg&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">termin\u00f3&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">los&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">sellos&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">en&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">solo&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">9,5&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">segundos&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">utilizando&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">robots&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">viper&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">articulados&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">de&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">6&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">ejes&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">de&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">OMRON&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">y&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">sysmac&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">studio&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">para&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">acelerar&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">su&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">producci\u00f3n.&nbsp;<\/span><\/span><\/h3>\n    \t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex flex-wrap gap-[0.75rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<a class=\"btn filled white  has-arrow\" type=\"button\" href=\"https:\/\/robotics.omron.com\/case-studies\/seal-finishing-automation-omron-trelleborg\/\" target=\"_self\">\n\t\t\t\t\t\t\t<svg width=\"13\" height=\"13\" viewbox=\"0 0 13 13\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t<path d=\"M8.55697 10.375L11.8486 6.94618L8.55697 3.51736\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t\t<path d=\"M1.01411 0.500006L1.0141 5.84896C1.0141 6.45463 1.50566 6.94618 2.11133 6.94618L11.9863 6.94618\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t<\/svg>\n\t\t\t\n\t\t\t<p>Ver la historia<\/p>\n\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<a class=\"btn has-border white  has-arrow\" type=\"button\" href=\"https:\/\/robotics.omron.com\/omron-robotics-case-studies\/\" target=\"_self\">\n\t\t\t\t\t\t\t<svg width=\"13\" height=\"13\" viewbox=\"0 0 13 13\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t<path d=\"M8.55697 10.375L11.8486 6.94618L8.55697 3.51736\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t\t<path d=\"M1.01411 0.500006L1.0141 5.84896C1.0141 6.45463 1.50566 6.94618 2.11133 6.94618L11.9863 6.94618\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t<\/svg>\n\t\t\t\n\t\t\t<p>Ver todos los estudios de \u00e9xito<\/p>\n\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"absolute top-0 left-0 h-full w-full opacity-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"h-full w-full max-w-[none]\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Viperrrrr-e1752511710778.jpg\"  loading=\"lazy\" alt=\"Robot articulado Viper\">\n\t\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\n\t<div class=\"ticker translate-y-[100%] bottom-0 left-0 ~w-[1.25rem]\/[1.875rem] ~h-[20rem]\/[28.125rem] z-[3] absolute pointer-events-none\">\n\t\t<svg class=\"w-full h-auto scale-y-[-1]\" width=\"31\" height=\"449\" viewbox=\"0 0 31 449\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t<line x1=\"15.75\" y1=\"-6.55671e-07\" x2=\"15.75\" y2=\"450\" stroke=\"url(#paint0_linear_7843_32626)\" stroke-width=\"30\" stroke-dasharray=\"3 7\"\/>\n\t\t\t<defs>\n\t\t\t\t<linearGradient id=\"paint0_linear_7843_32626\" x1=\"16.75\" y1=\"-6.99382e-07\" x2=\"15.334\" y2=\"450.005\" gradientunits=\"userSpaceOnUse\">\n\t\t\t\t\t<stop stop-color=\"#6AFF96\" stop-opacity=\"0\"\/>\n\t\t\t\t\t<stop offset=\"1\" stop-color=\"#6AFF96\"\/>\n\t\t\t\t<\/linearGradient>\n\t\t\t<\/defs>\n\t\t<\/svg>\n\t<\/div>\n<\/section>\n\n<section class=\"content-cta-band bg-white\">\n\t\n\t\t\n\t<div class=\"container\">\n\t\t<div class=\"st-xxl sb-xl\">\n\t\t\t<div class=\"box\">\n\t\t\t\t<div class=\"box-inner\">\n\t\t\t\t\t<div class=\"box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t        <h4 class=\"main-title text-white  flex flex-wrap\"><span class=\"outer-word\"><span class=\"inner-word\">Optimice&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">sus&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">flujos&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">de&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">trabajo&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">para&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">obtener&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">la&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">m\u00e1xima&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">productividad&nbsp;<\/span><\/span><\/h4>\n    \t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"lg text-white para-desc\">\u00bfTiene preguntas? Hablemos.  <\/p>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex flex-wrap gap-[0.75rem]\">\n\t\t\t\t\t\t\t\t                                    \t\t\t\n\t\t\t<a class=\"btn filled white  has-arrow\" type=\"button\" href=\"https:\/\/robotics.omron.com\/talk-to-an-expert\/\" target=\"_self\">\n\t\t\t\t\t\t\t<svg width=\"13\" height=\"13\" viewbox=\"0 0 13 13\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t<path d=\"M8.55697 10.375L11.8486 6.94618L8.55697 3.51736\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t\t<path d=\"M1.01411 0.500006L1.0141 5.84896C1.0141 6.45463 1.50566 6.94618 2.11133 6.94618L11.9863 6.94618\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t<\/svg>\n\t\t\t\n\t\t\t<p>Habla con un experto<\/p>\n\t\t<\/a>\n\t\t\t\t\t\t\t\t\t                                    \t\t\t\n\t\t\t<a class=\"btn has-border white  has-arrow\" type=\"button\" href=\"https:\/\/robotics.omron.com\/omron-robotics-case-studies\/\" target=\"_self\">\n\t\t\t\t\t\t\t<svg width=\"13\" height=\"13\" viewbox=\"0 0 13 13\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t<path d=\"M8.55697 10.375L11.8486 6.94618L8.55697 3.51736\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t\t<path d=\"M1.01411 0.500006L1.0141 5.84896C1.0141 6.45463 1.50566 6.94618 2.11133 6.94618L11.9863 6.94618\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t<\/svg>\n\t\t\t\n\t\t\t<p>Vea nuestros robots en acci\u00f3n<\/p>\n\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"box-image\">\n\t\t\t\t\t\t<div class=\"box-overlay\"><\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Pick-and-place-parallel-robots_OMRON_Robotics.jpg\"  loading=\"lazy\" alt=\"Pick-and-place-parallel-robots_OMRON_Robotics\">\n\t\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"content-product-list-carousel bg-white\">\n\t\n\t\t\n\t\n\t<div class=\"container\">\n\t\t<div class=\"st-xl sb-xl\">\n\t\t\t<div class=\"flex flex-col ~gap-[2.25rem]\/[3rem]\">\n\t\t\t\t<div class=\"w-full flex justify-between items-end\">\n\t\t\t\t\t<div class=\"flex flex-col ~gap-[1.25rem]\/[1.5rem] max-w-[48.375rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t        <h3 class=\"main-title  flex flex-wrap\">\t<div class=\"flex gap-[0.5rem] items-center shrink-0 align-top h-fit relative pt-[0.75rem] tracking-[normal] max-sm:w-full pb-[0.75rem]\">\n\t\t<div class=\"w-[0.5rem] h-[0.5rem] shrink-0 bg-green\"><\/div>\n\t\t<small class=\"text-black-60\">PRODUCTOS RELACIONADOS<\/small>\n\t<\/div>\n<span class=\"max-sm:hidden w-[5rem]\"><\/span><span class=\"outer-word\"><span class=\"inner-word\">Precisi\u00f3n,&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">velocidad&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">y&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">potencia&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">para&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">cada&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">necesidad&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">de&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">fabricaci\u00f3n&nbsp;<\/span><\/span><\/h3>\n    \t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"para-desc\">Maximice la producci\u00f3n y minimice el tiempo de inactividad con nuestra gama de robots industriales, dise\u00f1ados para la precisi\u00f3n, la durabilidad y la eficiencia en el montaje, el embalaje y la fabricaci\u00f3n de alta resistencia.<\/p>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"max-lg:hidden flex shrink-0 gap-[0.75rem] max-lg:justify-between\">\n\t\t\t\t\t\t<div class=\"ar-l bg-beige\">\n\t\t\t\t\t\t\t<svg width=\"20\" height=\"21\" viewbox=\"0 0 20 21\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t\t\t<path d=\"M13 16.1123L7 10.1123L13 4.1123\"\/>\n\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"ar-r bg-beige\">\n\t\t\t\t\t\t\t<svg width=\"20\" height=\"21\" viewbox=\"0 0 20 21\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t\t\t<path d=\"M7 4.1123L13 10.1123L7 16.1123\"\/>\n\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col gap-[1.25rem]\">\n\t\t\t\t\t\t<div class=\"relative box w-full\">\n\t\t\t\t\t\t\t<div class=\"swiper-container\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<a class=\"item swiper-slide\" href=\"https:\/\/robotics.omron.com\/products\/industrial-robots\/scara\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"~w-[15.25rem]\/[15.875rem] ~h-[13.625rem]\/[17.75rem] relative z-[2]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-contain relative z-[2]\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/i4h-650_0173-3.png?w=196\"  loading=\"eager\" alt=\"i4h 650_0173\">\n\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-orb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/webp\/hero-three-card-orb.webp\" loading=\"lazy\" alt=\"grid background\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"absolute top-0 left-0 h-full w-full pointer-events-none z-[1] opacity-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gradient-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"opacity-30\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/svg\/hero-three-card-grid.svg\" loading=\"lazy\" alt=\"grid background\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex gap-[1rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<small class=\"text-white-60 text-[0.75rem] relative top-[0.25rem]\">01<\/small>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"text-white flex-1\">Robots SCARA<\/h6>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"text-white\">R\u00e1pidos y precisos, los robots i4H, i4L y eCobra est\u00e1n dise\u00f1ados para tareas de montaje, manipulaci\u00f3n de materiales y embalaje de alto rendimiento.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<a class=\"item swiper-slide\" href=\"https:\/\/robotics.omron.com\/products\/industrial-robots\/parallel\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"~w-[15.25rem]\/[15.875rem] ~h-[13.625rem]\/[17.75rem] relative z-[2]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-contain relative z-[2]\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Omron-iX4-1728-TRANSPARENT-BG.png?w=248\"  loading=\"eager\" alt=\"Omron iX4 -1728 &#8211; TRANSPARENT BG\">\n\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-orb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/webp\/hero-three-card-orb.webp\" loading=\"lazy\" alt=\"grid background\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"absolute top-0 left-0 h-full w-full pointer-events-none z-[1] opacity-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gradient-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"opacity-30\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/svg\/hero-three-card-grid.svg\" loading=\"lazy\" alt=\"grid background\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex gap-[1rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<small class=\"text-white-60 text-[0.75rem] relative top-[0.25rem]\">02<\/small>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"text-white flex-1\">Robots paralelos<\/h6>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"text-white\">De alta velocidad y eficientes, los robots paralelos iX4\/Quattro e iX3\/Hornet destacan en aplicaciones de picking, packing y clasificaci\u00f3n.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<a class=\"item swiper-slide\" href=\"https:\/\/robotics.omron.com\/products\/industrial-robots\/articulated\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"~w-[15.25rem]\/[15.875rem] ~h-[13.625rem]\/[17.75rem] relative z-[2]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-contain relative z-[2]\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/OMRON-Viper-1.png?w=254\"  loading=\"eager\" alt=\"OMRON Viper\">\n\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-orb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/webp\/hero-three-card-orb.webp\" loading=\"lazy\" alt=\"grid background\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"absolute top-0 left-0 h-full w-full pointer-events-none z-[1] opacity-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gradient-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"opacity-30\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/svg\/hero-three-card-grid.svg\" loading=\"lazy\" alt=\"grid background\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex gap-[1rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<small class=\"text-white-60 text-[0.75rem] relative top-[0.25rem]\">03<\/small>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"text-white flex-1\">Robots articulados<\/h6>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"text-white\">Fiables y precisos, los robots articulados Viper de 6 ejes ofrecen un rendimiento excepcional en el mecanizado, el montaje y la manipulaci\u00f3n de materiales.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<a class=\"item swiper-slide\" href=\"https:\/\/robotics.omron.com\/products\/industrial-robots\/industrial-part-feeder\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"~w-[15.25rem]\/[15.875rem] ~h-[13.625rem]\/[17.75rem] relative z-[2]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-contain relative z-[2]\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/OMRON-industrial-part-feeder-iPF-530_Web-optmized.png?w=254\"  loading=\"eager\" alt=\"OMRON industrial part feeder &#8211; iPF-530_Web-optmized\">\n\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-orb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/webp\/hero-three-card-orb.webp\" loading=\"lazy\" alt=\"grid background\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"absolute top-0 left-0 h-full w-full pointer-events-none z-[1] opacity-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gradient-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"opacity-30\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/svg\/hero-three-card-grid.svg\" loading=\"lazy\" alt=\"grid background\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex gap-[1rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<small class=\"text-white-60 text-[0.75rem] relative top-[0.25rem]\">04<\/small>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"text-white flex-1\">Alimentadores de piezas industriales<\/h6>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"text-white\">Alimentadores flexibles y fiables que manipulan, clasifican y entregan piezas de cualquier forma o tama\u00f1o, agilizando el montaje automatizado.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<a class=\"item swiper-slide\" href=\"https:\/\/robotics.omron.com\/products\/industrial-robots\/robotics-integrated-controller\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"~w-[15.25rem]\/[15.875rem] ~h-[13.625rem]\/[17.75rem] relative z-[2]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-contain relative z-[2]\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/OMRON-Robotics-Integrated-Controller-with-i4L-SCARA-Robot.png?w=251\"  loading=\"eager\" alt=\"OMRON Robotics Integrated Controller with i4L SCARA Robot\">\n\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-orb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/webp\/hero-three-card-orb.webp\" loading=\"lazy\" alt=\"grid background\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"absolute top-0 left-0 h-full w-full pointer-events-none z-[1] opacity-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gradient-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"opacity-30\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/svg\/hero-three-card-grid.svg\" loading=\"lazy\" alt=\"grid background\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex gap-[1rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<small class=\"text-white-60 text-[0.75rem] relative top-[0.25rem]\">05<\/small>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"text-white flex-1\">Controlador integrado de rob\u00f3tica<\/h6>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"text-white\">Una unidad compacta que combina el control de movimiento, la E\/S y la comunicaci\u00f3n para una automatizaci\u00f3n rob\u00f3tica f\u00e1cil y precisa y una configuraci\u00f3n r\u00e1pida.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"orb scale-0 opacity-0 absolute top-0 left-0 h-[4rem] w-[4rem] bg-[rgba(38,38,38,0.90)] rounded-[50%] overflow-hidden flex items-center justify-center text-center z-[2] pointer-events-none\">\n\t\t\t\t\t\t\t\t\t<small class=\"text-white\">Arrastrar<\/small>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"lg:hidden flex shrink-0 gap-[0.75rem] max-lg:justify-between\">\n\t\t\t\t\t\t\t<div class=\"ar-l bg-beige\">\n\t\t\t\t\t\t\t\t<svg width=\"20\" height=\"21\" viewbox=\"0 0 20 21\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t\t\t\t<path d=\"M13 16.1123L7 10.1123L13 4.1123\"\/>\n\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"ar-r bg-beige\">\n\t\t\t\t\t\t\t\t<svg width=\"20\" height=\"21\" viewbox=\"0 0 20 21\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t\t\t\t<path d=\"M7 4.1123L13 10.1123L7 16.1123\"\/>\n\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"content-cta-large-image-bg bg-beige\">\n\t\n\t\t\n\t<div class=\"st-xxl sb-xl\">\n\t\t<div class=\"overflow-x-clip relative\">\n\t\t\t<div class=\"container w-full\">\n\t\t\t\t<div class=\"box  is-small\">\n\t\t\t\t\t<div class=\"content  is-left\">\n\t\t\t\t\t\t<div class=\"w-full md:max-w-[34.125rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t        <h3 class=\"main-title text-white  flex flex-wrap\">\t<div class=\"flex gap-[0.5rem] items-center shrink-0 align-top h-fit relative pt-[0.75rem] tracking-[normal] max-sm:w-full pb-[0.75rem]\">\n\t\t<div class=\"w-[0.5rem] h-[0.5rem] shrink-0 bg-green\"><\/div>\n\t\t<small class=\"text-white-60\">RECURSOS<\/small>\n\t<\/div>\n<span class=\"max-sm:hidden w-[5rem]\"><\/span><span class=\"outer-word\"><span class=\"inner-word\">Actualizaciones&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">y&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">documentaci\u00f3n&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">del&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">software&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">ACE&nbsp;<\/span><\/span><\/h3>\n    \t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col ~gap-[1.25rem]\/[1.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"para-desc text-white max-w-[31.625rem]\">Acceda a las \u00faltimas actualizaciones de software, archivos de soporte y manuales para optimizar los flujos de trabajo industriales y mantener su sistema actualizado.<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<a class=\"btn filled white  has-arrow\" type=\"button\" href=\"https:\/\/robotics.omron.com\/resources\/?id=20AE70F8-B006-44A9-A21340A27EC944F5\" target=\"_self\">\n\t\t\t\t\t\t\t<svg width=\"13\" height=\"13\" viewbox=\"0 0 13 13\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t<path d=\"M8.55697 10.375L11.8486 6.94618L8.55697 3.51736\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t\t<path d=\"M1.01411 0.500006L1.0141 5.84896C1.0141 6.45463 1.50566 6.94618 2.11133 6.94618L11.9863 6.94618\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t<\/svg>\n\t\t\t\n\t\t\t<p>Obtenga las \u00faltimas actualizaciones<\/p>\n\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"box-bg absolute w-full h-full min-w-[calc(100%+10rem)] min-h-[calc(100%+14rem)] z-[1] center-xy bg-black\" style=\"clip-path: inset(0% 0.5rem)\">\n\t\t\t\t\t\t<div class=\"box-overlay z-[2] absolute top-0 left-0 h-full w-full\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-image absolute top-0 left-0 h-full w-full\">\n\t\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-top\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Resources_OMRON-scaled.jpg?w=1192\"  loading=\"lazy\" alt=\"Resources_OMRON\">\n\t\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"resource-three-across-featured bg-beige\">\n\t\n\t\t\n\t<div class=\"container\">\n\t\t<div class=\"st-xl sb-xxl\">\n\t\t\t<div class=\"flex flex-col ~gap-[2.25rem]\/[3rem]\">\n\t\t\t\t<div class=\"flex max-md:flex-col gap-[1.5rem] justify-between md:items-end\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex-1 max-w-[39.25rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t        <h3 class=\"main-title  flex flex-wrap\"><span class=\"outer-word\"><span class=\"inner-word\">Informaci\u00f3n&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">relacionada&nbsp;<\/span><\/span><\/h3>\n    \t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t<a class=\"btn filled blue shrink-0  has-arrow\" type=\"button\" href=\"https:\/\/robotics.omron.com\/omron-robotics-case-studies\/\" target=\"_self\">\n\t\t\t\t\t\t\t<svg width=\"13\" height=\"13\" viewbox=\"0 0 13 13\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t<path d=\"M8.55697 10.375L11.8486 6.94618L8.55697 3.51736\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t\t<path d=\"M1.01411 0.500006L1.0141 5.84896C1.0141 6.45463 1.50566 6.94618 2.11133 6.94618L11.9863 6.94618\" stroke=\"white\" stroke-width=\"1.5\" stroke-miterlimit=\"10\"\/>\n\t\t\t\t<\/svg>\n\t\t\t\n\t\t\t<p>Ver toda la informaci\u00f3n<\/p>\n\t\t<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"items\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n                                                                                        \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                            \n\t\t\t\t\t\t\t<a class=\"blog-card resource-three-feature\" href=\"https:\/\/robotics.omron.com\/es\/case-studies\/fmcg-packaging-automation-vetipak\/\" >\n\t<div class=\"blog-card-inner\">\n\t\t<div class=\"flex flex-col gap-[0.75rem]\">\n\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"blog-card-image h-[11.5rem] rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/TS22-VETIPAK-OMRON-417.jpg?w=1024\"  loading=\"lazy\" alt=\"VETIPAK OMRON\">\n\t\n\n\t\t\t\n\t\t\t<div class=\"flex justify-between gap-[1.5rem]\">\n\t\t\t\t\t<div class=\"flex gap-[0.5rem] items-center \">\n\t\t<div class=\"w-[0.5rem] h-[0.5rem] shrink-0 bg-green\"><\/div>\n\t\t<small class=\"text-black-60\">Caso pr\u00e1ctico<\/small>\n\t<\/div>\n\t\t\t\t<small class=\"text-black-60\">9\/11\/2022<\/small>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<p class=\"lg\">El \u00e9xito escalable de Vetipak en la automatizaci\u00f3n de envasado de productos de gran consumo<\/p>\n\t<\/div>\n<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n                                                                                        \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                            \n\t\t\t\t\t\t\t<a class=\"blog-card resource-three-feature\" href=\"https:\/\/robotics.omron.com\/es\/case-studies\/automated-vial-labelling-omron-werfen\/\" >\n\t<div class=\"blog-card-inner\">\n\t\t<div class=\"flex flex-col gap-[0.75rem]\">\n\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"blog-card-image h-[11.5rem] rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Macco-Werfen-Operators-Cell.jpg?w=1024\"  loading=\"lazy\" alt=\"Macco-Werfen-Operators-Cell\">\n\t\n\n\t\t\t\n\t\t\t<div class=\"flex justify-between gap-[1.5rem]\">\n\t\t\t\t\t<div class=\"flex gap-[0.5rem] items-center \">\n\t\t<div class=\"w-[0.5rem] h-[0.5rem] shrink-0 bg-green\"><\/div>\n\t\t<small class=\"text-black-60\">Caso pr\u00e1ctico<\/small>\n\t<\/div>\n\t\t\t\t<small class=\"text-black-60\">14\/1\/2025<\/small>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<p class=\"lg\">\u00bfC\u00f3mo etiquetar werfen 1000 viales por hora con automatizaci\u00f3n?<\/p>\n\t<\/div>\n<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n                                                                                        \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                            \n\t\t\t\t\t\t\t<a class=\"blog-card resource-three-feature\" href=\"https:\/\/robotics.omron.com\/es\/case-studies\/automated-punnet-packing-omron\/\" >\n\t<div class=\"blog-card-inner\">\n\t\t<div class=\"flex flex-col gap-[0.75rem]\">\n\t\t\t\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"blog-card-image h-[11.5rem] rounded-[0.5rem] overflow-hidden\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Brillopak-Pick-Place-Machine-Carrot-Bags-1-e1752602237809.jpg?w=1024\"  loading=\"lazy\" alt=\"Brillopak-Pick-Place-Machine-Carrot-Bags (1)\">\n\t\n\n\t\t\t\n\t\t\t<div class=\"flex justify-between gap-[1.5rem]\">\n\t\t\t\t\t<div class=\"flex gap-[0.5rem] items-center \">\n\t\t<div class=\"w-[0.5rem] h-[0.5rem] shrink-0 bg-green\"><\/div>\n\t\t<small class=\"text-black-60\">Caso pr\u00e1ctico<\/small>\n\t<\/div>\n\t\t\t\t<small class=\"text-black-60\">11\/11\/2024<\/small>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<p class=\"lg\">C\u00f3mo la recolecci\u00f3n automatizada de cestas transform\u00f3 el envasado de productos frescos en brillopak<\/p>\n\t<\/div>\n<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":180846,"menu_order":48,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-180867","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Software ACE para robots industriales | Rob\u00f3tica OMRON<\/title>\n<meta name=\"description\" content=\"El software ACE de Omron optimiza la programaci\u00f3n y gesti\u00f3n de robots industriales con visi\u00f3n integrada, alimentaci\u00f3n y automatizaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/robotics.omron.com\/es\/products\/industrial-robots\/software\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Software ACE\" \/>\n<meta property=\"og:description\" content=\"El software ACE de Omron optimiza la programaci\u00f3n y gesti\u00f3n de robots industriales con visi\u00f3n integrada, alimentaci\u00f3n y automatizaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/robotics.omron.com\/es\/products\/industrial-robots\/software\/\" \/>\n<meta property=\"og:site_name\" content=\"OMRON Robotics\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T06:21:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/products\\\/industrial-robots\\\/software\\\/\",\"url\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/products\\\/industrial-robots\\\/software\\\/\",\"name\":\"Software ACE para robots industriales | Rob\u00f3tica OMRON\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/#website\"},\"datePublished\":\"2025-03-07T16:36:55+00:00\",\"dateModified\":\"2026-08-31T06:21:27+00:00\",\"description\":\"El software ACE de Omron optimiza la programaci\u00f3n y gesti\u00f3n de robots industriales con visi\u00f3n integrada, alimentaci\u00f3n y automatizaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/products\\\/industrial-robots\\\/software\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/robotics.omron.com\\\/es\\\/products\\\/industrial-robots\\\/software\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/products\\\/industrial-robots\\\/software\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descripci\u00f3n general del producto\",\"item\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Descripci\u00f3n general de los robots industriales\",\"item\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/products\\\/industrial-robots\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Software ACE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/\",\"name\":\"OMRON Robotics\",\"description\":\"Transforming Manufacturing Through Robotics\",\"publisher\":{\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/#organization\",\"name\":\"OMRON Robotics\",\"url\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/robotics.omron.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/OMRON_Logo.svg?w=1024\",\"contentUrl\":\"https:\\\/\\\/robotics.omron.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/OMRON_Logo.svg?w=1024\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"OMRON Robotics\"},\"image\":{\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/omron-robotics\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@OmronRoboticsAmericas\\\/featured\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Software ACE para robots industriales | Rob\u00f3tica OMRON","description":"El software ACE de Omron optimiza la programaci\u00f3n y gesti\u00f3n de robots industriales con visi\u00f3n integrada, alimentaci\u00f3n y automatizaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/robotics.omron.com\/es\/products\/industrial-robots\/software\/","og_locale":"es_ES","og_type":"article","og_title":"Software ACE","og_description":"El software ACE de Omron optimiza la programaci\u00f3n y gesti\u00f3n de robots industriales con visi\u00f3n integrada, alimentaci\u00f3n y automatizaci\u00f3n.","og_url":"https:\/\/robotics.omron.com\/es\/products\/industrial-robots\/software\/","og_site_name":"OMRON Robotics","article_modified_time":"2026-08-31T06:21:27+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/robotics.omron.com\/es\/products\/industrial-robots\/software\/","url":"https:\/\/robotics.omron.com\/es\/products\/industrial-robots\/software\/","name":"Software ACE para robots industriales | Rob\u00f3tica OMRON","isPartOf":{"@id":"https:\/\/robotics.omron.com\/es\/#website"},"datePublished":"2025-03-07T16:36:55+00:00","dateModified":"2026-08-31T06:21:27+00:00","description":"El software ACE de Omron optimiza la programaci\u00f3n y gesti\u00f3n de robots industriales con visi\u00f3n integrada, alimentaci\u00f3n y automatizaci\u00f3n.","breadcrumb":{"@id":"https:\/\/robotics.omron.com\/es\/products\/industrial-robots\/software\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/robotics.omron.com\/es\/products\/industrial-robots\/software\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/robotics.omron.com\/es\/products\/industrial-robots\/software\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/robotics.omron.com\/es\/"},{"@type":"ListItem","position":2,"name":"Descripci\u00f3n general del producto","item":"https:\/\/robotics.omron.com\/es\/products\/"},{"@type":"ListItem","position":3,"name":"Descripci\u00f3n general de los robots industriales","item":"https:\/\/robotics.omron.com\/es\/products\/industrial-robots\/"},{"@type":"ListItem","position":4,"name":"Software ACE"}]},{"@type":"WebSite","@id":"https:\/\/robotics.omron.com\/es\/#website","url":"https:\/\/robotics.omron.com\/es\/","name":"OMRON Robotics","description":"Transforming Manufacturing Through Robotics","publisher":{"@id":"https:\/\/robotics.omron.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/robotics.omron.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/robotics.omron.com\/es\/#organization","name":"OMRON Robotics","url":"https:\/\/robotics.omron.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/robotics.omron.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/08\/OMRON_Logo.svg?w=1024","contentUrl":"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/08\/OMRON_Logo.svg?w=1024","width":"1024","height":"1024","caption":"OMRON Robotics"},"image":{"@id":"https:\/\/robotics.omron.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/showcase\/omron-robotics\/","https:\/\/www.youtube.com\/@OmronRoboticsAmericas\/featured"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/robotics.omron.com\/es\/wp-json\/wp\/v2\/pages\/180867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robotics.omron.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/robotics.omron.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/robotics.omron.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/robotics.omron.com\/es\/wp-json\/wp\/v2\/comments?post=180867"}],"version-history":[{"count":3,"href":"https:\/\/robotics.omron.com\/es\/wp-json\/wp\/v2\/pages\/180867\/revisions"}],"predecessor-version":[{"id":199151,"href":"https:\/\/robotics.omron.com\/es\/wp-json\/wp\/v2\/pages\/180867\/revisions\/199151"}],"up":[{"embeddable":true,"href":"https:\/\/robotics.omron.com\/es\/wp-json\/wp\/v2\/pages\/180846"}],"wp:attachment":[{"href":"https:\/\/robotics.omron.com\/es\/wp-json\/wp\/v2\/media?parent=180867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}