{"id":182538,"date":"2025-04-25T02:15:05","date_gmt":"2025-04-25T09:15:05","guid":{"rendered":"https:\/\/robotics.omron.com\/parla-con-un-esperto\/"},"modified":"2026-03-24T17:18:42","modified_gmt":"2026-03-25T00:18:42","slug":"talk-to-an-expert","status":"publish","type":"page","link":"https:\/\/robotics.omron.com\/it\/talk-to-an-expert\/","title":{"rendered":"Parla con un esperto"},"content":{"rendered":"<section class=\"hero-form bg-beige\">\n\t\n\t<div class=\"container relative z-[2]\">\n\t\t<div class=\"~pt-[7.25rem]\/[10.25rem] sb-xxl\">\n\t\t\t<div class=\"flex max-lg:flex-col ~gap-[2.25rem]\/[8.75rem]\">\n\t\t\t\t<div class=\"lg:basis-[27rem] lg:flex-1\">\n\t\t\t\t\t<div class=\"flex flex-col ~gap-[1.25rem]\/[1.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\n\t\n\t        <h1 class=\"main-title  flex flex-wrap\"><span class=\"outer-word\"><span class=\"inner-word\">Parla&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">con&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">un&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">esperto&nbsp;<\/span><\/span><\/h1>\n    \n\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"para-desc\">Compila il modulo per richiedere una consulenza: un membro del nostro team ti contatter\u00e0 presto per fissare un appuntamento.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t                \n                                                    \n\t\t\t\t\t\t\t\t\t<div class=\"lg:basis-[48.375rem] lg:flex-1 ~min-h-[40.125rem]\/[33.75rem] bg-white ~p-[1.25rem]\/[3rem] rounded-[0.5rem] overflow-hidden\">\n\t\t\t\t\t\t<div class=\"form-container contact-us\" data-region=\"na2\" data-form-id=\"55dce4f0-7799-402d-bb8c-071ad9f290d7\" data-portal-id=\"47882041\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"parallax absolute left-[3.625rem] max-md:left-[unset] max-md:right-[0.5rem] ~bottom-[0rem]\/[-17rem]\">\n\t\t<img decoding=\"async\" class=\"~w-[15.375rem]\/[16.875rem] ~h-[41.125rem]\/[45rem] object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/svg\/hero-form.svg\" loading=\"lazy\" alt=\"background graphic\">\n\t<\/div>\n<\/section>\n\n\t<section class=\"content-full-width-parallax-image\">\n\t\t        \n\t\t<div class=\"overflow-hidden relative ~h-[23.625rem]\/[34.25rem] bg-pink-50\">\n\t\t\t<div class=\"parallax absolute center-y h-[180%] w-full\">\n\t\t\t\t\t\t\t\n        <img decoding=\"async\" class=\"object-cover max-w-none max-h-none min-h-full\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/SCARA_Robots_Lab_OMRON-scaled.jpg\"  loading=\"lazy\" alt=\"SCARA_Robots_Lab_OMRON\">\n\t\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<section class=\"content-location bg-white overflow-x-clip overflow-y-visible z-[2]\">\n\t\n\t\t\n\t\n\t<div class=\"container relative z-[2]\">\n\t\t<div class=\"st-xxl sb-xxl\">\n\t\t\t<div class=\"flex flex-col ~gap-[2.25rem]\/[3rem]\">\n\t\t\t\t<div class=\"max-w-[55.5rem]\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t        <h3 class=\"main-title  flex flex-wrap\">\t<div class=\"flex gap-[0.5rem] items-center shrink-0 align-top h-fit relative pt-[0.75rem] tracking-[normal] max-sm:w-full pb-[0.75rem]\">\n\t\t<div class=\"w-[0.5rem] h-[0.5rem] shrink-0 bg-green\"><\/div>\n\t\t<small class=\"text-black-60\">SEDI GLOBALI<\/small>\n\t<\/div>\n<span class=\"max-sm:hidden w-[5rem]\"><\/span><span class=\"outer-word\"><span class=\"inner-word\">La&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">nostra&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">rete&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">globale&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">di&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">robotica&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">\u2014&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">il&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">tuo&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">vantaggio&nbsp;<\/span><\/span><span class=\"outer-word\"><span class=\"inner-word\">locale&nbsp;<\/span><\/span><\/h3>\n    \t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"location-group\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n                            <div class=\"location-group-inner\">\n                                <div class=\"swiper-container\">\n                                    <div class=\"swiper-wrapper md:!grid md:!grid-cols-2 lg:!grid-cols-3 xl:!grid-cols-4 md:!gap-[1.5rem]\">\n                                                                                                                                    <div class=\"swiper-slide !h-auto\">\n                                                    <div class=\"h-full border-[0.0625rem] border-gray-2 p-[0.75rem] rounded-[0.5rem] bg-white flex flex-col gap-[0.75rem]\">\n                                                                                                                    <div class=\"h-[12.25rem]\">\n                                                                \t\t\t\n        <img decoding=\"async\" class=\"rounded-[0.5rem]\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/ORT_Headquarters-web_optimized-scaled.jpg?w=1024\"  loading=\"lazy\" alt=\"ORT_Headquarters-web_optimized\">\n\t\n\n                                                            <\/div>\n                                                        \n                                                        <div class=\"flex flex-col gap-[4rem] flex-1\">\n                                                                                                                            <h6>Sede centrale di Global &amp; Americas Robotics<\/h6>\n                                                            \n                                                            <div class=\"flex flex-col gap-[0.75rem] mt-auto\">\n                                                                                                                                    <div class=\"rich-text\"><p>4225 Hacienda Drive<br \/>\nPleasanton, CA 94588<br \/>\nUSA<\/p>\n<\/div>\n                                                                \n                                                                                                                                    <p>\n                                                                        <span>Tel:<\/span>\n                                                                        +1 (925) 245-3400 \n                                                                    <\/p>\n                                                                \n                                                                \n                                                                \n                                                                                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                                                                                                                <div class=\"swiper-slide !h-auto\">\n                                                    <div class=\"h-full border-[0.0625rem] border-gray-2 p-[0.75rem] rounded-[0.5rem] bg-white flex flex-col gap-[0.75rem]\">\n                                                                                                                    <div class=\"h-[12.25rem]\">\n                                                                \t\t\t\n        <img decoding=\"async\" class=\"rounded-[0.5rem]\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/OMRON-Europe-HQ.jpg?w=1024\"  loading=\"lazy\" alt=\"OMRON Europe HQ\">\n\t\n\n                                                            <\/div>\n                                                        \n                                                        <div class=\"flex flex-col gap-[4rem] flex-1\">\n                                                                                                                            <h6>Sede centrale europea<\/h6>\n                                                            \n                                                            <div class=\"flex flex-col gap-[0.75rem] mt-auto\">\n                                                                                                                                    <div class=\"rich-text\"><p>Wegalaan 57<br \/>\n2132 JD Hoofddorp<br \/>\nPaesi Bassi<\/p>\n<\/div>\n                                                                \n                                                                                                                                    <p>\n                                                                        <span>Tel:<\/span>\n                                                                        +31-23-5681200\n                                                                    <\/p>\n                                                                \n                                                                \n                                                                \n                                                                                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                                                                                                                <div class=\"swiper-slide !h-auto\">\n                                                    <div class=\"h-full border-[0.0625rem] border-gray-2 p-[0.75rem] rounded-[0.5rem] bg-white flex flex-col gap-[0.75rem]\">\n                                                                                                                    <div class=\"h-[12.25rem]\">\n                                                                \t\t\t\n        <img decoding=\"async\" class=\"rounded-[0.5rem]\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Kyoto_OMRON_Robotics-web-optimized-scaled.jpg?w=1024\"  loading=\"lazy\" alt=\"Kyoto_OMRON_Robotics-web-optimized\">\n\t\n\n                                                            <\/div>\n                                                        \n                                                        <div class=\"flex flex-col gap-[4rem] flex-1\">\n                                                                                                                            <h6>Sede centrale in Giappone<\/h6>\n                                                            \n                                                            <div class=\"flex flex-col gap-[0.75rem] mt-auto\">\n                                                                                                                                    <div class=\"rich-text\"><p>Shiokoji Horikawa<br \/>\nShimogyo-ku<br \/>\nKyoto 600-8530<br \/>\nGiappone<\/p>\n<\/div>\n                                                                \n                                                                                                                                    <p>\n                                                                        <span>Tel:<\/span>\n                                                                        0120-919-066 (from Japan)\n                                                                    <\/p>\n                                                                \n                                                                                                                                    <p>\n                                                                        <span>Tel:<\/span>\n                                                                        +81 0120-919-066 (from overseas)\n                                                                    <\/p>\n                                                                \n                                                                \n                                                                                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                                                                                                                <div class=\"swiper-slide !h-auto\">\n                                                    <div class=\"h-full border-[0.0625rem] border-gray-2 p-[0.75rem] rounded-[0.5rem] bg-white flex flex-col gap-[0.75rem]\">\n                                                                                                                    <div class=\"h-[12.25rem]\">\n                                                                \t\t\t\n        <img decoding=\"async\" class=\"rounded-[0.5rem]\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/09\/Korean-HQ-Seoul.jpg?w=684\"  loading=\"lazy\" alt=\"Korean HQ, Seoul\">\n\t\n\n                                                            <\/div>\n                                                        \n                                                        <div class=\"flex flex-col gap-[4rem] flex-1\">\n                                                                                                                            <h6>Sede centrale in Corea del Sud<\/h6>\n                                                            \n                                                            <div class=\"flex flex-col gap-[0.75rem] mt-auto\">\n                                                                                                                                    <div class=\"rich-text\"><p>18th Floor, B Building<br \/>\n465 Gangnam-daero, Seocho-gu<br \/>\nSeoul<br \/>\nCorea del Sud<\/p>\n<\/div>\n                                                                \n                                                                                                                                    <p>\n                                                                        <span>Tel:<\/span>\n                                                                        +82 70-4506-4106\n                                                                    <\/p>\n                                                                \n                                                                \n                                                                \n                                                                                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                                                                                                                <div class=\"swiper-slide !h-auto\">\n                                                    <div class=\"h-full border-[0.0625rem] border-gray-2 p-[0.75rem] rounded-[0.5rem] bg-white flex flex-col gap-[0.75rem]\">\n                                                                                                                    <div class=\"h-[12.25rem]\">\n                                                                \t\t\t\n        <img decoding=\"async\" class=\"rounded-[0.5rem]\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Singapore_Asia_Pacific_web-optimized-scaled.jpg?w=1024\"  loading=\"lazy\" alt=\"Singapore_Asia_Pacific_web-optimized\">\n\t\n\n                                                            <\/div>\n                                                        \n                                                        <div class=\"flex flex-col gap-[4rem] flex-1\">\n                                                                                                                            <h6>Sede centrale Asia-Pacifico<\/h6>\n                                                            \n                                                            <div class=\"flex flex-col gap-[0.75rem] mt-auto\">\n                                                                                                                                    <div class=\"rich-text\"><p>438B Alexandra Road, #08-01\/02<br \/>\nAlexandra Technopark<br \/>\nSingapore 119968<br \/>\n<a href=\"https:\/\/www.omron-ap.com\/sales-network\" target=\"_blank\" rel=\"noopener\">Connettiti con il tuo team locale<\/a><\/p>\n<\/div>\n                                                                \n                                                                                                                                    <p>\n                                                                        <span>Tel:<\/span>\n                                                                        (65) 6835-3011\n                                                                    <\/p>\n                                                                \n                                                                \n                                                                \n                                                                                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                                                                                                                <div class=\"swiper-slide !h-auto\">\n                                                    <div class=\"h-full border-[0.0625rem] border-gray-2 p-[0.75rem] rounded-[0.5rem] bg-white flex flex-col gap-[0.75rem]\">\n                                                                                                                    <div class=\"h-[12.25rem]\">\n                                                                \t\t\t\n        <img decoding=\"async\" class=\"rounded-[0.5rem]\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Shanghai_OMRON_web-optimized-1-scaled.jpg?w=1024\"  loading=\"lazy\" alt=\"Shanghai_OMRON_web-optimized\">\n\t\n\n                                                            <\/div>\n                                                        \n                                                        <div class=\"flex flex-col gap-[4rem] flex-1\">\n                                                                                                                            <h6>Ufficio della Cina continentale<\/h6>\n                                                            \n                                                            <div class=\"flex flex-col gap-[0.75rem] mt-auto\">\n                                                                                                                                    <div class=\"rich-text\"><p>Room 2211, Bank of China Building<br \/>\nNo. 200 Yincheng Middle Road, Pudong New Area<br \/>\nShanghai, 200120<br \/>\nCina<\/p>\n<\/div>\n                                                                \n                                                                                                                                    <p>\n                                                                        <span>Tel:<\/span>\n                                                                        +86 021-60230333\n                                                                    <\/p>\n                                                                \n                                                                \n                                                                \n                                                                                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                                                                                                                <div class=\"swiper-slide !h-auto\">\n                                                    <div class=\"h-full border-[0.0625rem] border-gray-2 p-[0.75rem] rounded-[0.5rem] bg-white flex flex-col gap-[0.75rem]\">\n                                                                                                                    <div class=\"h-[12.25rem]\">\n                                                                \t\t\t\n        <img decoding=\"async\" class=\"rounded-[0.5rem]\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/07\/Taipei-Taiwan-Regional-Office.jpg?w=1024\"  loading=\"lazy\" alt=\"Taipei &#8211; Taiwan Regional Office\">\n\t\n\n                                                            <\/div>\n                                                        \n                                                        <div class=\"flex flex-col gap-[4rem] flex-1\">\n                                                                                                                            <h6>Ufficio di Taiwan<\/h6>\n                                                            \n                                                            <div class=\"flex flex-col gap-[0.75rem] mt-auto\">\n                                                                                                                                    <div class=\"rich-text\"><p>6F Home Young Bldg.<br \/>\nNo. 363 Fu-Shing North Rd.<br \/>\nTaipei<br \/>\nTaiwan<\/p>\n<\/div>\n                                                                \n                                                                                                                                    <p>\n                                                                        <span>Tel:<\/span>\n                                                                        (+886)-2-2715-3331\n                                                                    <\/p>\n                                                                \n                                                                \n                                                                \n                                                                                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                                                                                                                <div class=\"swiper-slide !h-auto\">\n                                                    <div class=\"h-full border-[0.0625rem] border-gray-2 p-[0.75rem] rounded-[0.5rem] bg-white flex flex-col gap-[0.75rem]\">\n                                                                                                                    <div class=\"h-[12.25rem]\">\n                                                                \t\t\t\n        <img decoding=\"async\" class=\"rounded-[0.5rem]\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Mumbai_regional_office_India-web-optimized-scaled.jpg?w=1024\"  loading=\"lazy\" alt=\"Mumbai_regional_office_India-web-optimized\">\n\t\n\n                                                            <\/div>\n                                                        \n                                                        <div class=\"flex flex-col gap-[4rem] flex-1\">\n                                                                                                                            <h6>Ufficio in India<\/h6>\n                                                            \n                                                            <div class=\"flex flex-col gap-[0.75rem] mt-auto\">\n                                                                                                                                    <div class=\"rich-text\"><p>Ground Floor, L3 Block<br \/>\nHazel Manyata Embassy Business Park<br \/>\nOuter Ring Road Nagavara<br \/>\nBengaluru, Karnataka 560045<br \/>\nIndia<\/p>\n<\/div>\n                                                                \n                                                                                                                                    <p>\n                                                                        <span>Tel:<\/span>\n                                                                        (+91-22) 7128-8400\n                                                                    <\/p>\n                                                                \n                                                                \n                                                                \n                                                                                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                                                                                                                <div class=\"swiper-slide !h-auto\">\n                                                    <div class=\"h-full border-[0.0625rem] border-gray-2 p-[0.75rem] rounded-[0.5rem] bg-white flex flex-col gap-[0.75rem]\">\n                                                                                                                    <div class=\"h-[12.25rem]\">\n                                                                \t\t\t\n        <img decoding=\"async\" class=\"rounded-[0.5rem]\" src=\"https:\/\/robotics.omron.com\/wp-content\/uploads\/Sao_Paulo_Brazil_web-optimized-scaled.jpg?w=1024\"  loading=\"lazy\" alt=\"Sao_Paulo_Brazil_web-optimized\">\n\t\n\n                                                            <\/div>\n                                                        \n                                                        <div class=\"flex flex-col gap-[4rem] flex-1\">\n                                                                                                                            <h6>Ufficio in Brasile<\/h6>\n                                                            \n                                                            <div class=\"flex flex-col gap-[0.75rem] mt-auto\">\n                                                                                                                                    <div class=\"rich-text\"><p>Alameda Vicente Pinzon, 51 &#8211; 14\u00b0 Piano<br \/>\nVila Olimpia, CEP: 04547-130<br \/>\nS\u00e3o Paulo<br \/>\nBrasile<\/p>\n<\/div>\n                                                                \n                                                                                                                                    <p>\n                                                                        <span>Tel:<\/span>\n                                                                        +55-11-5039-2110\n                                                                    <\/p>\n                                                                \n                                                                \n                                                                \n                                                                                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                                                        <\/div>\n                                <\/div>\n\n                                <div class=\"lg:hidden flex shrink-0 gap-[0.75rem] ~mt-[1.25rem]\/[1.5rem] max-lg:justify-between\">\n                                    <div class=\"ar-l !bg-beige\">\n                                        <svg width=\"20\" height=\"21\" viewbox=\"0 0 20 21\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                            <path d=\"M13 16.1123L7 10.1123L13 4.1123\"\/>\n                                        <\/svg>\n                                    <\/div>\n\n                                    <div class=\"ar-r !bg-beige\">\n                                        <svg width=\"20\" height=\"21\" viewbox=\"0 0 20 21\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                            <path d=\"M7 4.1123L13 10.1123L7 16.1123\"\/>\n                                        <\/svg>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"parallax absolute ~right-[-12.125rem]\/[-6.625rem] ~top-[13rem]\/[8.75rem]\">\n\t\t<img decoding=\"async\" class=\"~w-[31.5rem]\/[47.375rem] ~h-[31.5rem]\/[47.375rem] object-contain\" src=\"https:\/\/robotics.omron.com\/wp-content\/themes\/omron\/assets\/img\/svg\/globe.svg\" loading=\"lazy\" alt=\"background graphic\">\n\t<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":83,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-182538","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Parla con un esperto | OMRON Robotics<\/title>\n<meta name=\"description\" content=\"Mettiti in contatto con un esperto di OMRON Robotics per ricevere consigli personalizzati e soluzioni su misura per le tue esigenze di automazione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/robotics.omron.com\/it\/talk-to-an-expert\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parla con un esperto\" \/>\n<meta property=\"og:description\" content=\"Mettiti in contatto con un esperto di OMRON Robotics per ricevere consigli personalizzati e soluzioni su misura per le tue esigenze di automazione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/robotics.omron.com\/it\/talk-to-an-expert\/\" \/>\n<meta property=\"og:site_name\" content=\"OMRON Robotics\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T00:18:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/it\\\/talk-to-an-expert\\\/\",\"url\":\"https:\\\/\\\/robotics.omron.com\\\/it\\\/talk-to-an-expert\\\/\",\"name\":\"Parla con un esperto | OMRON Robotics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/it\\\/#website\"},\"datePublished\":\"2025-04-25T09:15:05+00:00\",\"dateModified\":\"2026-03-25T00:18:42+00:00\",\"description\":\"Mettiti in contatto con un esperto di OMRON Robotics per ricevere consigli personalizzati e soluzioni su misura per le tue esigenze di automazione.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/it\\\/talk-to-an-expert\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/robotics.omron.com\\\/it\\\/talk-to-an-expert\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/it\\\/talk-to-an-expert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/robotics.omron.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parla con un esperto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/robotics.omron.com\\\/it\\\/\",\"name\":\"OMRON Robotics\",\"description\":\"Transforming Manufacturing Through Robotics\",\"publisher\":{\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/robotics.omron.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/it\\\/#organization\",\"name\":\"OMRON Robotics\",\"url\":\"https:\\\/\\\/robotics.omron.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/robotics.omron.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/OMRON_Logo.svg?w=1024\",\"contentUrl\":\"https:\\\/\\\/robotics.omron.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/OMRON_Logo.svg?w=1024\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"OMRON Robotics\"},\"image\":{\"@id\":\"https:\\\/\\\/robotics.omron.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/omron-robotics\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@OmronRoboticsAmericas\\\/featured\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Parla con un esperto | OMRON Robotics","description":"Mettiti in contatto con un esperto di OMRON Robotics per ricevere consigli personalizzati e soluzioni su misura per le tue esigenze di automazione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/robotics.omron.com\/it\/talk-to-an-expert\/","og_locale":"it_IT","og_type":"article","og_title":"Parla con un esperto","og_description":"Mettiti in contatto con un esperto di OMRON Robotics per ricevere consigli personalizzati e soluzioni su misura per le tue esigenze di automazione.","og_url":"https:\/\/robotics.omron.com\/it\/talk-to-an-expert\/","og_site_name":"OMRON Robotics","article_modified_time":"2026-03-25T00:18:42+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/robotics.omron.com\/it\/talk-to-an-expert\/","url":"https:\/\/robotics.omron.com\/it\/talk-to-an-expert\/","name":"Parla con un esperto | OMRON Robotics","isPartOf":{"@id":"https:\/\/robotics.omron.com\/it\/#website"},"datePublished":"2025-04-25T09:15:05+00:00","dateModified":"2026-03-25T00:18:42+00:00","description":"Mettiti in contatto con un esperto di OMRON Robotics per ricevere consigli personalizzati e soluzioni su misura per le tue esigenze di automazione.","breadcrumb":{"@id":"https:\/\/robotics.omron.com\/it\/talk-to-an-expert\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/robotics.omron.com\/it\/talk-to-an-expert\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/robotics.omron.com\/it\/talk-to-an-expert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/robotics.omron.com\/it\/"},{"@type":"ListItem","position":2,"name":"Parla con un esperto"}]},{"@type":"WebSite","@id":"https:\/\/robotics.omron.com\/it\/#website","url":"https:\/\/robotics.omron.com\/it\/","name":"OMRON Robotics","description":"Transforming Manufacturing Through Robotics","publisher":{"@id":"https:\/\/robotics.omron.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/robotics.omron.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/robotics.omron.com\/it\/#organization","name":"OMRON Robotics","url":"https:\/\/robotics.omron.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/robotics.omron.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/08\/OMRON_Logo.svg?w=1024","contentUrl":"https:\/\/robotics.omron.com\/wp-content\/uploads\/2025\/08\/OMRON_Logo.svg?w=1024","width":"1024","height":"1024","caption":"OMRON Robotics"},"image":{"@id":"https:\/\/robotics.omron.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/showcase\/omron-robotics\/","https:\/\/www.youtube.com\/@OmronRoboticsAmericas\/featured"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/robotics.omron.com\/it\/wp-json\/wp\/v2\/pages\/182538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robotics.omron.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/robotics.omron.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/robotics.omron.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/robotics.omron.com\/it\/wp-json\/wp\/v2\/comments?post=182538"}],"version-history":[{"count":3,"href":"https:\/\/robotics.omron.com\/it\/wp-json\/wp\/v2\/pages\/182538\/revisions"}],"predecessor-version":[{"id":184656,"href":"https:\/\/robotics.omron.com\/it\/wp-json\/wp\/v2\/pages\/182538\/revisions\/184656"}],"wp:attachment":[{"href":"https:\/\/robotics.omron.com\/it\/wp-json\/wp\/v2\/media?parent=182538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}